{"id":274891,"date":"2024-05-08T17:19:47","date_gmt":"2024-05-08T09:19:47","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/one-hit-wonder-rocket-man-tobacco-free-nic-salt-e-juice-2\/"},"modified":"2026-06-23T18:21:08","modified_gmt":"2026-06-23T10:21:08","slug":"one-hit-wonder-rocket-man-tobacco-free-nic-salt-e-juice","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/de\/produkt\/one-hit-wonder-rocket-man-tobacco-free-nic-salt-e-juice\/","title":{"rendered":"One Hit Wonder Rocket Man Tobacco-Free Nic Salt E-Juice 100ml &#8211; Blueberry, Greek Yogurt, and Granola Blend"},"content":{"rendered":"<h2>One Hit Wonder Rocket Man Tabakfreier Nikotinsalz-E-Saft 100ml<\/h2>\n<ul class=\"top\">\n<li>Marke: One Hit Wonder<\/li>\n<li>Einheit: eingestellt<\/li>\n<li>Typ: Vape-Saft<\/li>\n<li>Nettogewicht: 105(g)<\/li>\n<\/ul>\n<p>Die kombinierten Versandkosten werden vom System automatisch berechnet, nachdem Sie im Schritt zur Kasse das Versandziel ausgew\u00e4hlt haben.<\/p>\n<div class=\"title\">One Hit Wonder Rocket Man TF-Nic Salt E-Saft 100ml EINF\u00dcHRUNG<\/div>\n<p>One Hit Wonder Rocket Man vereint einen leicht s\u00e4uerlichen griechischen Joghurt, frische Bergblaubeeren und herzhaftes M\u00fcsli im 100ml-Beh\u00e4lter. Der klassische Geschmack ergibt eine harmonische Mischung mit reinem tabakfreiem Salznikotin, das in der Joghurtwelt seinesgleichen sucht. Machen Sie sich bereit f\u00fcr einen Geschmack, der nicht von dieser Welt ist, von der subtilen s\u00fc\u00dfen S\u00e4ure beim Einatmen bis zum reinigenden Ausatmen des Gaumens! Genie\u00dfen Sie die Fahrt!<\/p>\n<p>Nikotinsalze:\u00a0<span style=\"color: #ce0000\">Nikotinsalz-E-Saft wurde speziell f\u00fcr Pod-basierte Ger\u00e4te und andere Konfigurationen mit geringer Leistung und hohem Widerstand entwickelt. Nic Salt wird nicht f\u00fcr die Verwendung mit RDAs oder Sub-Ohm-Tanks und -Ger\u00e4ten empfohlen.<\/span><\/p>\n<p class=\"second-title\">Funktionen<\/p>\n<p>\u2022 Griechischer Joghurt, Blaubeere, M\u00fcsli<\/p>\n<p>\u2022 100mL Squeeze-Einhorn-Flasche<\/p>\n<p>\u2022 30% VG<\/p>\n<p>\u2022 70% PG<\/p>\n<p>\u2022 100% Hergestellt in den USA<\/p>\n<p>\u2022 Hergestellt mit Trunic 2.0 Nikotinsalzen<\/p>\n<p>\u2022 Erh\u00e4ltlich in Salz TF-Nic: 0 mg, 3 mg, 6 mg<\/p>\n<div class=\"title\">One Hit Wonder Rocket Man TF-Nic Salt E-Saft 100ml SPEZIFIKATION<\/div>\n<p>Flaschengr\u00f6\u00dfe: 100ml<\/p>\n<p>Verh\u00e4ltnismischung: 30VG\/70PG<\/p>\n<p>Nikotingehalt: TF-Nic 0 mg, TF-Nic 3 mg, TF-Nic 6 mg<\/p>\n<p>Geschmacksprofil: Griechischer Joghurt, Blaubeere, M\u00fcsli<\/p>\n<div class=\"title\">One Hit Wonder Rocket Man TF-Nic Salt E-Saft 100ml PAKETLISTE<\/div>\n<p>1 Flasche X One Hit Wonder Rocket Man TF-Nic Salt E-Saft<\/p>\n","protected":false},"excerpt":{"rendered":"<p>One Hit Wonder Rocket Man Tabakfreier Nikotinsalz-E-Saft 100ml Marke: One Hit Wonder Einheit: eingestellt Typ: Vape-Saft Nettogewicht: 105(g) Die kombinierten Versandkosten werden vom System automatisch berechnet, nachdem Sie im Schritt zur Kasse das Versandziel ausgew\u00e4hlt haben. One Hit Wonder Rocket Man TF-Nic Salt E-Saft 100ml EINF\u00dcHRUNG One Hit Wonder Rocket Man vereint einen leicht s\u00e4uerlichen [&#8230;]\n","protected":false},"featured_media":132458,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3065],"product_tag":[],"class_list":["post-274891","product","type-product","status-publish","has-post-thumbnail","product_cat-e-liquids-de","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/product\/274891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/comments?post=274891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/media\/132458"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/media?parent=274891"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/product_brand?post=274891"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/product_cat?post=274891"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/product_tag?post=274891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}