{"id":275071,"date":"2024-05-07T11:30:07","date_gmt":"2024-05-07T03:30:07","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/cool-mint-blast-vape-juice-2\/"},"modified":"2026-06-23T18:35:44","modified_gmt":"2026-06-23T10:35:44","slug":"cool-mint-blast-vape-juice","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/de\/produkt\/cool-mint-blast-vape-juice\/","title":{"rendered":"Cool Mint Blast Vape Juice \u2013 Twist Mint No.1 E-Saft 60 ml"},"content":{"rendered":"<h2>Twist Mint No.1 E-Saft<\/h2>\n<ul class=\"top\">\n<li style=\"list-style-type: none\">\n<ul class=\"top\">\n<li>Marke:\u00a0<b>Twist<\/b><\/li>\n<li>Einheit: eingestellt<\/li>\n<li>Typ:\u00a0<b>Vape Juice<\/b><\/li>\n<li>Nettogewicht: 105(g)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Die kombinierten Versandkosten werden vom System automatisch berechnet, nachdem Sie im Schritt zur Kasse das Versandziel ausgew\u00e4hlt haben.<\/p>\n<div class=\"title\">Twist Mint No.1 E-Saft EINF\u00dcHRUNG<\/div>\n<p><b>Twist Mint No.1 E-Saft<\/b>\u00a0erm\u00f6glicht es Ihnen, in die verlockende Umarmung eisiger Minze einzutauchen, wo Sie jeder Zug in eine frostgek\u00fcsste Oase entf\u00fchrt. Mit einer sorgf\u00e4ltig zusammengestellten Mischung liefert dieser E-Saft einen Hauch reiner Minz-Erregung, die an eine frische Bergbrise erinnert. Die belebenden Noten von gr\u00fcner Minze und Pfefferminze tanzen auf Ihrem Gaumen und schaffen eine harmonische Fusion, die sowohl k\u00fchlend als auch befriedigend ist. Egal, ob Sie ein erfahrener Dampfer oder ein Neuling sind.<\/p>\n<p class=\"second-title\">Funktionen<\/p>\n<p>\u2022 60 ml*2 Einhornflasche<\/p>\n<p>\u2022 Kindersichere Kappe<\/p>\n<p>\u2022 70% VG<\/p>\n<p>\u2022 30% PG<\/p>\n<p>\u2022 Synthetische Nikotinformulierung<\/p>\n<p>\u2022 Hergestellt in den USA<\/p>\n<p>\u2022 Erh\u00e4ltlich in 3 mg, 6 mg<\/p>\n<div class=\"title\">PAKETLISTE f\u00fcr Twist Mint No.1 E-Liquid<\/div>\n<p>1 * Twist Mint No.1 E-Saft<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Twist Mint No.1 E-Saft Marke:\u00a0Twist Einheit: eingestellt Typ:\u00a0Vape Juice Nettogewicht: 105(g) Die kombinierten Versandkosten werden vom System automatisch berechnet, nachdem Sie im Schritt zur Kasse das Versandziel ausgew\u00e4hlt haben. Twist Mint No.1 E-Saft EINF\u00dcHRUNG Twist Mint No.1 E-Saft\u00a0erm\u00f6glicht es Ihnen, in die verlockende Umarmung eisiger Minze einzutauchen, wo Sie jeder Zug in eine frostgek\u00fcsste Oase [&#8230;]\n","protected":false},"featured_media":339764,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3065],"product_tag":[],"class_list":["post-275071","product","type-product","status-publish","has-post-thumbnail","product_cat-e-liquids-de","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/product\/275071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/comments?post=275071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/media\/339764"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/media?parent=275071"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/product_brand?post=275071"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/product_cat?post=275071"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/product_tag?post=275071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}