{"id":298945,"date":"2023-09-28T15:52:37","date_gmt":"2023-09-28T07:52:37","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/boho-horizon-10000-puffs-disposable-vape-wholesale-2\/"},"modified":"2026-07-08T17:33:47","modified_gmt":"2026-07-08T09:33:47","slug":"boho-horizon-10000-puffs-disposable-vape-wholesale","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/de\/produkt\/boho-horizon-10000-puffs-disposable-vape-wholesale\/","title":{"rendered":"BOHO Horizon 10000 Puffs Einweg-Vape-Gro\u00dfhandel, glatter Dampf, hohe Kapazit\u00e4t"},"content":{"rendered":"<h2>BOHO Horizon 10000 Puffs Einweg-Vape-Gro\u00dfhandel, glatter Dampf, hohe Kapazit\u00e4t Grosshandelsueberblick<\/h2>\n<p>BOHO Horizon 10000 Puffs Einweg-Vape-Gro\u00dfhandel, glatter Dampf, hohe Kapazit\u00e4t ist als klare Grosshandelsseite fuer Einweg-Vape aufgebaut, damit Kaeufer 10000 Zuege und Grosshandelsgerechte Praesentation vergleichen koennen, ohne wiederholte Lieferantentexte durchsuchen zu muessen.<\/p>\n<h2>Wichtige Merkmale<\/h2>\n<ul>\n<li><strong>10000 Zuege<\/strong> &#8211; macht den erwarteten Nutzungsbereich fuer einen schnellen Vergleich sichtbar<\/li>\n<li><strong>Grosshandelsgerechte Praesentation<\/strong> &#8211; haelt die Seite praktisch fuer Shops, Distributoren und Mengenbestellungen<\/li>\n<\/ul>\n<h2>Spezifikationen<\/h2>\n<table>\n<tbody>\n<tr>\n<td><strong>Produktname<\/strong><\/td>\n<td>BOHO Horizon 10000 Puffs Einweg-Vape-Gro\u00dfhandel, glatter Dampf, hohe Kapazit\u00e4t<\/td>\n<\/tr>\n<tr>\n<td><strong>Produkttyp<\/strong><\/td>\n<td>Einweg-Vape<\/td>\n<\/tr>\n<tr>\n<td><strong>Zuege<\/strong><\/td>\n<td>10000 Zuege<\/td>\n<\/tr>\n<tr>\n<td><strong>Einsatz fuer Kaeufer<\/strong><\/td>\n<td>Grosshandel, Einzelhandel und Katalogplanung fuer Distributoren<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Grosshandelsnotizen<\/h2>\n<p>Nutzen Sie diese Seite, um das Modell mit aehnlichen Grosshandelsartikeln nach Zugzahl, Kapazitaet, Geraeteformat, Bedienfunktionen und Praesentation im Regal zu vergleichen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>BOHO Horizon 10000 Puffs<\/strong> bietet eine hohe Kapazit\u00e4t und gleichm\u00e4\u00dfigen Dampf und ist somit eine zuverl\u00e4ssige Wahl f\u00fcr l\u00e4ngeres Dampfen.<\/p>\n","protected":false},"featured_media":122455,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2726,2738,2725],"product_tag":[3681],"class_list":["post-298945","product","type-product","status-publish","has-post-thumbnail","product_cat-verfugbar","product_cat-10000-puffs-einweg-vape","product_cat-verschiedene-zuge-von-einweg-vapes","product_tag-beste-einweg-vape-auf-verkauf","first","onbackorder","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":{"1000":18,"10000":16,"50000":14},"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":100,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/product\/298945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/comments?post=298945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/media\/122455"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/media?parent=298945"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/product_brand?post=298945"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/product_cat?post=298945"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/de\/wp-json\/wp\/v2\/product_tag?post=298945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}