{"id":267686,"date":"2024-05-30T11:57:10","date_gmt":"2024-05-30T03:57:10","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/geekvape-s100-box-mod-aegis-solo-2-100w-2\/"},"modified":"2026-06-23T14:15:58","modified_gmt":"2026-06-23T06:15:58","slug":"geekvape-s100-box-mod-aegis-solo-2-100w","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/es\/producto\/geekvape-s100-box-mod-aegis-solo-2-100w\/","title":{"rendered":"Geekvape S100 Box Mod (Aegis Solo 2) 100W: Vape 18650 \u00fanico y resistente con resistencia al agua y al polvo IP68 y caracter\u00edsticas de seguridad mejoradas"},"content":{"rendered":"<h2>Geekvape S100 Caja Mod (Aegis Solo 2 Mod)<\/h2>\n<ul class=\"top\">\n<li>Marca: Geekvape<\/li>\n<li>Unidad: conjunto<\/li>\n<li>Tipo: Caja Mod<\/li>\n<li>Peso neto: 160(g)<\/li>\n<\/ul>\n<p>El sistema calcular\u00e1 autom\u00e1ticamente el costo de env\u00edo combinado despu\u00e9s de que usted elija el destino de env\u00edo en el paso de pago.<\/p>\n<div class=\"title\">Geekvape S100 Caja Mod INTRODUCCI\u00d3N<\/div>\n<p><b>Mod de caja Geekvape S100<\/b> funciona con una sola bater\u00eda externa 18650 (no incluida) y admite hasta salida 100W. El puerto de carga tipo C con tapa abatible garantiza en gran medida la seguridad de este mod y simplifica la operaci\u00f3n de carga hasta cierto punto. Este mod tambi\u00e9n utiliza un dise\u00f1o de protecci\u00f3n contra pulsaciones accidentales para evitar que la bobina se queme demasiado o el sobrecalentamiento del mod causado por una pulsaci\u00f3n accidental. La segunda generaci\u00f3n de Geekvape Tri-proof Tech le otorga a este mod IP68 una clasificaci\u00f3n de resistencia al agua y al polvo y un mayor nivel de resistencia a los golpes. La pantalla grande de 1.08-inch puede permitir que cada detalle del producto se refleje en la pantalla, brind\u00e1ndole una mejor experiencia visual. As\u00ed que date prisa y compra este mod, su calidad superar\u00e1 tus expectativas.<\/p>\n<p class=\"second-title\">Caracter\u00edsticas<\/p>\n<p>\u2022 Admite hasta salida 100W<\/p>\n<p>\u2022 Bater\u00eda \u00fanica externa 18650 (no incluida)<\/p>\n<p>\u2022 Salida de potencia m\u00e1xima 100W<\/p>\n<p>\u2022 Puerto de carga tipo C con tapa abatible<\/p>\n<p>\u2022 Deslizar el interruptor hacia arriba\/abajo<\/p>\n<p>\u2022 Dise\u00f1o de protecci\u00f3n contra prensa accidental<\/p>\n<p>\u2022 Clasificaci\u00f3n IP68 de resistencia al agua y al polvo.<\/p>\n<p>\u2022 Mayor nivel de resistencia a los golpes<\/p>\n<p>\u2022 1.Pantalla completa 08-inch<\/p>\n<div class=\"title\">ESPECIFICACI\u00d3N del mod de caja Geekvape S100<\/div>\n<div class=\"specification\">\n<div class=\"splist\"><em>Pantalla de visualizaci\u00f3n:<\/em>1.08 pulgadas, pantalla a color TFT<\/div>\n<div class=\"splist\"><em>Rango de resistencia:<\/em>0.1-3.0ohm<\/div>\n<div class=\"splist\"><em>Puerto de carga: <\/em>Puerto tipo C<\/div>\n<div class=\"splist\"><em>Dimensiones:<\/em>86.5*39.6*30.3mm<\/div>\n<div class=\"splist\"><em>Tiempo de vapeo m\u00e1s largo:<\/em>10\u00b11s<\/div>\n<div class=\"splist\"><em>Bater\u00eda: <\/em>Bater\u00eda \u00fanica externa 18650 (no incluida)<\/div>\n<div class=\"splist\"><em>Potencia m\u00e1xima:<\/em>100W<\/div>\n<div class=\"splist\"><em>Colores: <\/em>Plata, Gris, Negro Cl\u00e1sico, Azul Marino, Rojo, Arco Iris<\/div>\n<\/div>\n<div class=\"title\">LISTA DE PAQUETES Geekvape S100 Box Mod<\/div>\n<p>EDICI\u00d3N EST\u00c1NDAR<\/p>\n<p>1 Mod de caja Geekvape S100<\/p>\n<p>1 cable USB (tipo C)<\/p>\n<p>1 manual de usuario.<\/p>\n<div class=\"title\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Geekvape S100 Box Mod (Aegis Solo 2) 100W: Rugged Single 18650 Vape with IP68 Water &amp; Dust Resistance and Enhanced Safety Features VAPE HK SHOP | WHOLESALE\" src=\"https:\/\/i0.wp.com\/image.vapesourcing.com\/images\/202108\/Geekvape-S100-Box-Mod-1_%282%29.png?w=1020&#038;ssl=1\" alt=\"Geekvape S100 Mod features\" \/>\u00a0<img data-recalc-dims=\"1\" decoding=\"async\" title=\"Geekvape S100 Box Mod (Aegis Solo 2) 100W: Rugged Single 18650 Vape with IP68 Water &amp; Dust Resistance and Enhanced Safety Features VAPE HK SHOP | WHOLESALE\" src=\"https:\/\/i0.wp.com\/image.vapesourcing.com\/images\/202108\/Geekvape-S100-Box-Mod-1_%281%29.png?w=1020&#038;ssl=1\" alt=\"Geekvape S100 Mod for sale\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Geekvape S100 Caja Mod (Aegis Solo 2 Mod) Marca: Geekvape Unidad: conjunto Tipo: Caja Mod Peso neto: 160(g) El sistema calcular\u00e1 autom\u00e1ticamente el costo de env\u00edo combinado despu\u00e9s de que usted elija el destino de env\u00edo en el paso de pago. Geekvape S100 Caja Mod INTRODUCCI\u00d3N Mod de caja Geekvape S100 funciona con una sola [&#8230;]\n","protected":false},"featured_media":134590,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2810],"product_tag":[],"class_list":["post-267686","product","type-product","status-publish","has-post-thumbnail","product_cat-caja-mod","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product\/267686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/comments?post=267686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/media\/134590"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/media?parent=267686"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_brand?post=267686"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_cat?post=267686"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_tag?post=267686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}