{"id":274682,"date":"2024-05-09T11:12:23","date_gmt":"2024-05-09T03:12:23","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/skwezed-ice-watermelon-mint-2\/"},"modified":"2026-06-23T18:04:31","modified_gmt":"2026-06-23T10:04:31","slug":"skwezed-ice-watermelon-mint","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/es\/producto\/skwezed-ice-watermelon-mint\/","title":{"rendered":"SKWEZED ICE Watermelon Mint Flavor Jugo para vapear 100ml"},"content":{"rendered":"<h2>SKWEZED ICE E-jugo de sand\u00eda 100ml<\/h2>\n<ul>\n<li>Marca:\u00a0<b>SKWEZED<\/b><\/li>\n<li>Unidad: conjunto<\/li>\n<li>Tipo:\u00a0<b>Jugo para vapear<\/b><\/li>\n<li>Peso neto: 100(g)<\/li>\n<\/ul>\n<p>El sistema calcular\u00e1 autom\u00e1ticamente el costo de env\u00edo combinado despu\u00e9s de que usted elija el destino de env\u00edo en el paso de pago.<\/p>\n<div class=\"title\">SKWEZED ICE E-jugo de sand\u00eda 100ml INTRODUCCI\u00d3N<\/div>\n<p>El e-jugo de sand\u00eda SKWEZED ICE tiene tres niveles de nicotina para que usted elija y tambi\u00e9n llena una botella de e-jugo 100ml llena. Desde el momento en que inhalas este delicioso e-jugo de sand\u00eda helada, recordar\u00e1s las fragantes praderas y el c\u00e1lido y puro sol y cielo del verano. A diferencia de otro e-jugo con sabor a sand\u00eda, SKWEZED ICE Watermelon tambi\u00e9n tiene una mezcla de menta fresca en el e-jugo para brindarte una experiencia de vapeo como probar una sand\u00eda fr\u00eda. Cuando inhalas, el rico sabor de la sand\u00eda brinda el m\u00e1ximo confort y cuando exhalas, el frescor de la menta se mezcla con la dulzura de la sand\u00eda madura. Al brindarle el disfrute \u00fanico del regusto, es una excelente opci\u00f3n de vapeo que nunca podr\u00e1 perderse en verano.<\/p>\n<div class=\"title\">ESPECIFICACI\u00d3N 100ml del jugo electr\u00f3nico de sand\u00eda SKWEZED ICE<\/div>\n<div>\n<div class=\"splist\"><em>Tama\u00f1o de la botella:<\/em>100ml<\/div>\n<div class=\"splist\"><em>Mezcla de proporci\u00f3n:<\/em>70VG\/30PG<\/div>\n<div class=\"splist\"><em>Nivel de nicotina:<\/em>0 mg, 3 mg, 6 mg<\/div>\n<div class=\"splist\"><em>Perfil de sabor:<\/em>Sand\u00eda, mentol<\/div>\n<\/div>\n<div class=\"title\">SKWEZED ICE E-jugo de sand\u00eda 100ml LISTA DE PAQUETES<\/div>\n<p>1 botella X SKWEZED ICE E-jugo de sand\u00eda<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SKWEZED ICE E-jugo de sand\u00eda 100ml Marca:\u00a0SKWEZED Unidad: conjunto Tipo:\u00a0Jugo para vapear Peso neto: 100(g) El sistema calcular\u00e1 autom\u00e1ticamente el costo de env\u00edo combinado despu\u00e9s de que usted elija el destino de env\u00edo en el paso de pago. SKWEZED ICE E-jugo de sand\u00eda 100ml INTRODUCCI\u00d3N El e-jugo de sand\u00eda SKWEZED ICE tiene tres niveles de [&#8230;]\n","protected":false},"featured_media":132571,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2815],"product_tag":[],"class_list":["post-274682","product","type-product","status-publish","has-post-thumbnail","product_cat-e-liquidos","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product\/274682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/comments?post=274682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/media\/132571"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/media?parent=274682"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_brand?post=274682"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_cat?post=274682"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_tag?post=274682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}