{"id":274796,"date":"2024-05-09T10:27:54","date_gmt":"2024-05-09T02:27:54","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/pod-juice-pj5000-watermelon-bubblegum-2\/"},"modified":"2026-06-23T18:13:33","modified_gmt":"2026-06-23T10:13:33","slug":"pod-juice-pj5000-watermelon-bubblegum","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/es\/producto\/pod-juice-pj5000-watermelon-bubblegum\/","title":{"rendered":"Pod Juice PJ5000 Watermelon Bubblegum Nic Salt Jugo para vapear 30ml"},"content":{"rendered":"<h2>Jugo electr\u00f3nico de chicle de sand\u00eda serie Pod Juice PJ5000<\/h2>\n<ul>\n<li>Marca:\u00a0<b>Jugo de vaina<\/b><\/li>\n<li>Unidad: conjunto<\/li>\n<li>Tipo:\u00a0<b>Jugo para vapear<\/b><\/li>\n<li>Peso neto: 75(g)<\/li>\n<\/ul>\n<p>El sistema calcular\u00e1 autom\u00e1ticamente el costo de env\u00edo combinado despu\u00e9s de que usted elija el destino de env\u00edo en el paso de pago.<\/p>\n<div class=\"title\">Jugo electr\u00f3nico Pod Juice PJ5000 Series Sand\u00eda Bubblegum INTRODUCCI\u00d3N<\/div>\n<p><b>Pod Juice PJ5000 Series Watermelon Bubblegum E-juice<\/b> ofrece 30 ml de jugo para vapear con sabor a mezcla de frutas y dulces con sal de nicotina. Los vapeadores ocasionales y los principiantes pueden tomar la versi\u00f3n de 35 mg para obtener caladas m\u00e1s suaves. A los vapeadores empedernidos les pueden gustar los niveles altos de nicotina y los fuertes golpes en la garganta. Simplemente sue\u00f1a con sand\u00edas frescas y jugosas y dulces explotando en tu boca. Que los sabores fr\u00edos y dulces vienen con la calma. Elige PJ5000 y el jugo para vapear Bubblegum de sand\u00eda ser\u00e1 tu salvador en el caluroso verano.<\/p>\n<p class=\"segundo-t\u00edtulo\">Caracter\u00edsticas<\/p>\n<p>\u2022 Botella Gorila Gordita 30ml<\/p>\n<p>\u2022 50%VG<\/p>\n<p>\u2022 50%PG<\/p>\n<p>\u2022 Formulaci\u00f3n de nicotina sint\u00e9tica<\/p>\n<p>\u2022 Fabricado en EE. UU.<\/p>\n<p>\u2022 Fabricado por Liquid Labs<\/p>\n<p>\u2022 Nicotina disponible: 35 mg, 55 mg<\/p>\n<div class=\"title\">Jugo electr\u00f3nico de chicle de sand\u00eda serie PJ5000 LISTA DE PAQUETES<\/div>\n<p>1 x E-jugo de chicle de sand\u00eda serie PJ5000 Pod Juice<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jugo electr\u00f3nico de chicle de sand\u00eda serie Pod Juice PJ5000 Marca:\u00a0Jugo de vaina Unidad: conjunto Tipo:\u00a0Jugo para vapear Peso neto: 75(g) El sistema calcular\u00e1 autom\u00e1ticamente el costo de env\u00edo combinado despu\u00e9s de que usted elija el destino de env\u00edo en el paso de pago. Jugo electr\u00f3nico Pod Juice PJ5000 Series Sand\u00eda Bubblegum INTRODUCCI\u00d3N Pod Juice [&#8230;]\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2815],"product_tag":[],"class_list":["post-274796","product","type-product","status-publish","product_cat-e-liquidos","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product\/274796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/comments?post=274796"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/media?parent=274796"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_brand?post=274796"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_cat?post=274796"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_tag?post=274796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}