{"id":274820,"date":"2024-05-08T17:40:42","date_gmt":"2024-05-08T09:40:42","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/pj5000-series-kiwi-dragon-berry-nic-salt-e-juice-2\/"},"modified":"2026-06-23T18:15:25","modified_gmt":"2026-06-23T10:15:25","slug":"pj5000-series-kiwi-dragon-berry-nic-salt-e-juice","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/es\/producto\/pj5000-series-kiwi-dragon-berry-nic-salt-e-juice\/","title":{"rendered":"PJ5000 Series Kiwi Dragon Berry Nic Salt E-Juice by Jugo de vaina de 30 ml: mezcla ex\u00f3tica de kiwi, fruta del drag\u00f3n y bayas, opciones con alto contenido de nicotina disponibles"},"content":{"rendered":"<h2>Jugo electr\u00f3nico Pod Juice PJ5000 Series Kiwi Dragon Berry<\/h2>\n<ul>\n<li>Marca:\u00a0<b>Jugo de vaina<\/b><\/li>\n<li>Unidad: conjunto<\/li>\n<li>Tipo:\u00a0<b>Jugo para vapear<\/b><\/li>\n<li>Peso neto: 75(g)<\/li>\n<\/ul>\n<p>El sistema calcular\u00e1 autom\u00e1ticamente el costo de env\u00edo combinado despu\u00e9s de que usted elija el destino de env\u00edo en el paso de pago.<\/p>\n<div class=\"title\">Jugo electr\u00f3nico Pod Juice PJ5000 Series Kiwi Dragon Berry INTRODUCCI\u00d3N<\/div>\n<p><b>El jugo electr\u00f3nico Pod Juice PJ5000 Series Kiwi Dragon Berry<\/b> viene con 30 ml de jugo para vapear, 35 mg o 55 mg de sal de nicotina y sabores de frutas deliciosamente mezclados, que incluyen kiwi, pitahaya y bayas. El jugo electr\u00f3nico Kiwi Dragon Berry es popular debido a sus sabores mixtos. Las tres frutas tienen sabores \u00fanicos y todos estos sabores est\u00e1n bien conservados y separados. Basta una calada para disfrutar de tres frutas ex\u00f3ticas de diferentes perfiles. La sal de nicotina es f\u00e1cil de absorber y eficaz. Llena tu tanque con tres sabores de frutas diferentes en una botella.<\/p>\n<p class=\"segundo-t\u00edtulo\">Caracter\u00edsticas<\/p>\n<p>\u2022 Botella Gorila Gordita 30ml<\/p>\n<p>\u2022 50%VG<\/p>\n<p>\u2022 50%PG<\/p>\n<p>\u2022 Formulaci\u00f3n de nicotina sint\u00e9tica<\/p>\n<p>\u2022 Fabricado en EE. UU.<\/p>\n<p>\u2022 Fabricado por Liquid Labs<\/p>\n<p>\u2022 Nicotina disponible: 35 mg, 55 mg<\/p>\n<div class=\"title\">Pod Juice PJ5000 Series Kiwi Dragon Berry E-juice LISTA DE PAQUETES<\/div>\n<p>1 x E-jugo Pod Juice PJ5000 Series Kiwi Dragon Berry<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jugo electr\u00f3nico Pod Juice PJ5000 Series Kiwi Dragon Berry Marca:\u00a0Jugo de vaina Unidad: conjunto Tipo:\u00a0Jugo para vapear Peso neto: 75(g) El sistema calcular\u00e1 autom\u00e1ticamente el costo de env\u00edo combinado despu\u00e9s de que usted elija el destino de env\u00edo en el paso de pago. Jugo electr\u00f3nico Pod Juice PJ5000 Series Kiwi Dragon Berry INTRODUCCI\u00d3N El jugo [&#8230;]\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2815],"product_tag":[],"class_list":["post-274820","product","type-product","status-publish","product_cat-e-liquidos","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product\/274820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/comments?post=274820"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/media?parent=274820"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_brand?post=274820"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_cat?post=274820"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_tag?post=274820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}