{"id":275072,"date":"2024-05-07T11:30:07","date_gmt":"2024-05-07T03:30:07","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/cool-mint-blast-vape-juice-2\/"},"modified":"2026-06-23T18:35:46","modified_gmt":"2026-06-23T10:35:46","slug":"cool-mint-blast-vape-juice","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/es\/producto\/cool-mint-blast-vape-juice\/","title":{"rendered":"Cool Mint Blast Jugo para vapear &#8211; Jugo electr\u00f3nico Twist Mint No.1 60 ml"},"content":{"rendered":"<h2>E-jugo Twist Mint No.1<\/h2>\n<ul>\n<li>\n<ul>\n<li>Marca:\u00a0<b>Twist<\/b><\/li>\n<li>Unidad: conjunto<\/li>\n<li>Tipo:\u00a0<b>Jugo para vapear<\/b><\/li>\n<li>Peso neto: 105(g)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>El sistema calcular\u00e1 autom\u00e1ticamente el costo de env\u00edo combinado despu\u00e9s de que usted elija el destino de env\u00edo en el paso de pago.<\/p>\n<div class=\"title\">Jugo electr\u00f3nico Twist Mint No.1 INTRODUCCI\u00d3N<\/div>\n<p><b>Twist Mint No.1 E-juice<\/b>\u00a0te permite sumergirte en el tentador abrazo de la menta helada, donde cada inhalaci\u00f3n te transporta a un oasis ba\u00f1ado por la escarcha. Con una mezcla meticulosamente elaborada, este e-liquid ofrece una explosi\u00f3n de pura euforia mentolada, que recuerda a una fuerte brisa de monta\u00f1a. Las vigorizantes notas de menta verde y menta bailan en tu paladar, creando una fusi\u00f3n armoniosa que es a la vez refrescante y satisfactoria. Ya seas un vapeador experimentado o un reci\u00e9n llegado.<\/p>\n<p class=\"segundo-t\u00edtulo\">Caracter\u00edsticas<\/p>\n<p>\u2022 Botella Unicornio de 60ml*2<\/p>\n<p>\u2022 Gorra resistente a ni\u00f1os<\/p>\n<p>\u2022 70%VG<\/p>\n<p>\u2022 30%PG<\/p>\n<p>\u2022 Formulaci\u00f3n de nicotina sint\u00e9tica<\/p>\n<p>\u2022 Fabricado en EE. UU.<\/p>\n<p>\u2022 Disponible en 3 mg, 6 mg<\/p>\n<div class=\"title\">LISTA DE PAQUETES del jugo electr\u00f3nico Twist Mint No.1<\/div>\n<p>1 * E-jugo Twist Mint No.1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E-jugo Twist Mint No.1 Marca:\u00a0Twist Unidad: conjunto Tipo:\u00a0Jugo para vapear Peso neto: 105(g) El sistema calcular\u00e1 autom\u00e1ticamente el costo de env\u00edo combinado despu\u00e9s de que usted elija el destino de env\u00edo en el paso de pago. Jugo electr\u00f3nico Twist Mint No.1 INTRODUCCI\u00d3N Twist Mint No.1 E-juice\u00a0te permite sumergirte en el tentador abrazo de la menta [&#8230;]\n","protected":false},"featured_media":339765,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2815],"product_tag":[],"class_list":["post-275072","product","type-product","status-publish","has-post-thumbnail","product_cat-e-liquidos","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product\/275072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/comments?post=275072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/media\/339765"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/media?parent=275072"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_brand?post=275072"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_cat?post=275072"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_tag?post=275072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}