{"id":275432,"date":"2024-04-30T10:51:57","date_gmt":"2024-04-30T02:51:57","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/glas-vapor-butterscotch-reserve-2\/"},"modified":"2026-06-23T19:05:23","modified_gmt":"2026-06-23T11:05:23","slug":"glas-vapor-butterscotch-reserve","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/es\/producto\/glas-vapor-butterscotch-reserve\/","title":{"rendered":"Zumo para vapear Glas Vapor Butterscotch Reserve &#8211; Basix Series E-Juice 60ml &#8211; Rich Tobacco and Velvety Butterscotch Flavor"},"content":{"rendered":"<h2>Glas Vapor Reserva de Caramelo &#8211; Basix Series E-juice 60ml<\/h2>\n<ul>\n<li>Marca:\u00a0<b>Glas Vapor<\/b><\/li>\n<li>Unidad: conjunto<\/li>\n<li>Tipo:\u00a0<b>Jugo para vapear<\/b><\/li>\n<li>Peso neto: 60(g)<\/li>\n<\/ul>\n<p>El sistema calcular\u00e1 autom\u00e1ticamente el costo de env\u00edo combinado despu\u00e9s de que usted elija el destino de env\u00edo en el paso de pago.<\/p>\n<div class=\"title\">INTRODUCCI\u00d3N<\/div>\n<p>Este jugo electr\u00f3nico Butterscotch Reserve de la serie Glas Vapor Basix ofrece una rica bocanada de sabores audaces de tabaco y caramelo aterciopelado. Viene en frascos 60ml con concentraciones de nicotina de 0 mg, 3 mg y 6 mg. El puerto de llenado Unicorn de la botella es f\u00e1cil de llenar. Este delicioso sabor es muy adecuado para tu atomizador y generar\u00e1 una gran nube de vapeo.<\/p>\n<div class=\"title\">ESPECIFICACI\u00d3N<\/div>\n<div>\n<div class=\"splist\"><em>Tama\u00f1o de la botella<\/em>60ml<\/div>\n<div class=\"splist\"><em>Tipo de botella<\/em>Unicornio<\/div>\n<div class=\"splist\"><em>Relaci\u00f3n VG\/PG<\/em>70\/30<\/div>\n<div class=\"splist\"><em>Nivel de NIC<\/em>0 mg, 3 mg, 6 mg<\/div>\n<div class=\"splist\"><em>Sabor<\/em>Caramelo, Tabaco<\/div>\n<\/div>\n<div class=\"title\">LISTA DE PAQUETES<\/div>\n<p>1 botella x Glas Vapor Butterscotch Reserve &#8211; Basix Series E-juice 60ml<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Glas Vapor Reserva de Caramelo &#8211; Basix Series E-juice 60ml Marca:\u00a0Glas Vapor Unidad: conjunto Tipo:\u00a0Jugo para vapear Peso neto: 60(g) El sistema calcular\u00e1 autom\u00e1ticamente el costo de env\u00edo combinado despu\u00e9s de que usted elija el destino de env\u00edo en el paso de pago. INTRODUCCI\u00d3N Este jugo electr\u00f3nico Butterscotch Reserve de la serie Glas Vapor Basix [&#8230;]\n","protected":false},"featured_media":132155,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2815],"product_tag":[],"class_list":["post-275432","product","type-product","status-publish","has-post-thumbnail","product_cat-e-liquidos","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product\/275432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/comments?post=275432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/media\/132155"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/media?parent=275432"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_brand?post=275432"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_cat?post=275432"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_tag?post=275432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}