{"id":277696,"date":"2023-11-14T18:23:53","date_gmt":"2023-11-14T10:23:53","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/smok-novo-bar-al9000-9000-puffs-disposable-vape-wholesale-2\/"},"modified":"2026-06-23T21:28:47","modified_gmt":"2026-06-23T13:28:47","slug":"smok-novo-bar-al9000-9000-puffs-disposable-vape-wholesale","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/es\/producto\/smok-novo-bar-al9000-9000-puffs-disposable-vape-wholesale\/","title":{"rendered":"SMOK Novo Bar AL9000 9000 sopla estructura recargable duradera al por mayor desechable de Vape"},"content":{"rendered":"<h2>Vaporizador desechable SMOK Novo Bar AL9000<\/h2>\n<ul>\n<li>\n<ul>\n<li>Marca:\u00a0<b>SMOK<\/b><b><\/b><\/li>\n<li>Unidad: conjunto<\/li>\n<li>Tipo:\u00a0<b>Vaporizador desechable<\/b><\/li>\n<li>Peso neto: 90(g)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>El sistema calcular\u00e1 autom\u00e1ticamente el costo de env\u00edo combinado despu\u00e9s de que usted elija el destino de env\u00edo en el paso de pago.<\/p>\n<div class=\"title\">SMOK Novo Bar AL9000 Vape desechable INTRODUCCI\u00d3N<\/div>\n<p><b>El vaporizador desechable SMOK Novo Bar AL9000<\/b>\u00a0est\u00e1 equipado con un e-l\u00edquido precargado de 15 ml y una bater\u00eda recargable de 800 mAh, que puede ofrecer vapeo de hasta inhalaciones 9000. La concentraci\u00f3n de nicotina de 50 mg puede brindarle la experiencia de vapeo ideal y exacta. El acabado en contraste de colores y su marco en forma de caja aportan un dise\u00f1o luminoso y armonioso. Con su salida m\u00e1xima 17W y una bobina de malla integrada, puede mejorar el sabor original mediante un interruptor de flujo de aire desde la parte inferior.<\/p>\n<p class=\"segundo-t\u00edtulo\">Caracter\u00edsticas<\/p>\n<p>\u2022 Tama\u00f1o: 45.8*27*83.9mm<\/p>\n<p>\u2022 15 ml de jugo para vapear precargado<\/p>\n<p>\u2022 Sal de Nic al 5 % (50 mg)<\/p>\n<p>\u2022 Bater\u00eda recargable de 800 mAh<\/p>\n<p>\u2022 Puerto USB-C<\/p>\n<p>\u2022 Aproximadamente 9000 Puffs<\/p>\n<p>\u2022 Bobina de malla<\/p>\n<p>\u2022 Activado por sorteo<\/p>\n<p>\u2022 Indicadores de l\u00edquido y bater\u00eda<\/p>\n<p>\u2022 Potencia m\u00e1xima de 17W<\/p>\n<p>\u2022 0.77A Corriente de carga<\/p>\n<p>\u2022 Interruptor de flujo de aire<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SMOK Novo Bar AL9000 ofrece caladas 9000, ofreciendo una construcci\u00f3n duradera y recargable para experiencias de vapeo duraderas.<\/p>\n","protected":false},"featured_media":126475,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2812,2878,2811],"product_tag":[4675],"class_list":["post-277696","product","type-product","status-publish","has-post-thumbnail","product_cat-desechable","product_cat-vapes-desechables-de-9000-caladas","product_cat-diferentes-caladas-de-vapes-desechables","product_tag-mejor-vape-desechable-en-venta","first","instock","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":{"1000":14,"10000":12,"50000":10},"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":100,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product\/277696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/comments?post=277696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/media\/126475"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/media?parent=277696"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_brand?post=277696"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_cat?post=277696"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_tag?post=277696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}