{"id":329674,"date":"2021-02-24T15:49:30","date_gmt":"2021-02-24T07:49:30","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/yuoto-acme-vape-pod-system-kit-wholesale-2\/"},"modified":"2026-06-24T09:46:20","modified_gmt":"2026-06-24T01:46:20","slug":"yuoto-acme-vape-pod-system-kit-wholesale","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/es\/producto\/yuoto-acme-vape-pod-system-kit-wholesale\/","title":{"rendered":"Kit de sistema de c\u00e1psulas para vapeo Yuoto ACME | Venta al por mayor"},"content":{"rendered":"<h3>Color:<\/h3>\n<p><label class=\"SizeSwatch\" for=\"option-product-template-0-0\">Negro<\/label><\/p>\n<p><label class=\"SizeSwatch\" for=\"option-product-template-0-1\">Colorful<\/label><\/p>\n<p>\u00a0<\/p>\n<h3>Detalles:<\/h3>\n<p>Tama\u00f1o: 95.5*40*18mm<br \/>\nPeso: 90g<br \/>\nResistencia: 0,7\u03a9<br \/>\nCorriente de carga: 5V-1A<br \/>\nTama\u00f1o del embalaje: 115*86*29 mm (con un mod, un m\u00f3dulo PCTG y un cable de carga USB)<br \/>\nTama\u00f1o del embalaje del n\u00facleo atomizador: 90*45*15 mm (3 unidades por paquete)<\/p>\n<p>Modo de ahorro de energ\u00eda: cuando no necesite la luz, presione el bot\u00f3n de encendido 3 veces para apagar la funci\u00f3n de luz.<\/p>\n<p>Caracter\u00edsticas: 6 luces de colores<\/p>\n<p>Capacidad de bater\u00eda extra grande<\/p>\n<p>Dispositivo perfecto para principiantes y perfecto para Nic-salt.<\/p>\n<p>Gran capacidad de almacenamiento de E-liquid<\/p>\n<p>El chip desarrollado recientemente por el equipo de California utiliza los dos conjuntos superior e inferior de la versi\u00f3n del programa, viene con una funci\u00f3n de monitoreo en tiempo real y ajusta continuamente la potencia de salida requerida por el e-juice para la influencia del flujo de aire en la bobina de calentamiento. No es necesario ajustar la operaci\u00f3n, todos los ajustes autom\u00e1ticos inteligentes le brindan la mejor experiencia.<\/p>\n<p>Capacidad de almacenamiento de e-l\u00edquido de 4ML que satisface las necesidades diarias del usuario en lugar de recargas frecuentes. El material en contacto con el e-l\u00edquido es material PCTG de calidad alimentaria, que tiene una alta estabilidad y evita cualquier reacci\u00f3n adversa con el e-l\u00edquido. Al mismo tiempo, el POD est\u00e1 equipado con un n\u00facleo atomizador terminado con una resistencia de 0,7 \u03a9. Bajo el fuerte empuj\u00f3n del chip, el vapor y el sabor conviven y el sabor del vapor es perfecto.<\/p>\n<p>Luces LED 24, 6 colores disponibles. Cuando quieras cambiar el color a usar, solo necesitas agitar el MOD. El chip interno est\u00e1 equipado con un componente sensor de vibraci\u00f3n de alta sensibilidad. Cuando no se requiere luz ambiental, simplemente presione el bot\u00f3n de encendido tres veces para apagarlo y luego se puede usar la bater\u00eda para aumentar su duraci\u00f3n. Cae la noche, cuando caminas por la calle, est\u00e1s en el foco de atenci\u00f3n de todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Capacidad de la bater\u00eda: 1200 mAh<br \/>\nMaterial (MOD):ABS de aleaci\u00f3n de aluminio<br \/>\nMaterial (POD): algod\u00f3n PCTG<br \/>\nCapacidad: 4ML<\/p>\n","protected":false},"featured_media":326556,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2822],"product_tag":[5139],"class_list":["post-329674","product","type-product","status-publish","has-post-thumbnail","product_cat-kits-de-inicio","product_tag-yuoto-es","first","instock","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":{"30":26.5,"50":24.5},"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product\/329674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/comments?post=329674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/media\/326556"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/media?parent=329674"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_brand?post=329674"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_cat?post=329674"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_tag?post=329674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}