{"id":330214,"date":"2020-11-11T12:23:46","date_gmt":"2020-11-11T04:23:46","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/gippro-gp6-japan-food-standard-vape-starter-kit-1device-and-2-pods-2\/"},"modified":"2026-06-24T08:43:22","modified_gmt":"2026-06-24T00:43:22","slug":"gippro-gp6-japan-food-standard-vape-starter-kit-1device-and-2-pods","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/es\/producto\/gippro-gp6-japan-food-standard-vape-starter-kit-1device-and-2-pods\/","title":{"rendered":"Kit Gippro GP6 Japan Starter (1 dispositivo y 2 pods)"},"content":{"rendered":"<h1>Gippro GP6 ingenio japon\u00e9s<\/h1>\n<div>El \u00faltimo producto de Gippro GP6 es m\u00e1s popular en Jap\u00f3n. Su apariencia de moda hace que se convierta en una nueva tendencia entre los zurdos y existe una versi\u00f3n sin nicotina. \u00a1Est\u00e1 dise\u00f1ado para usted que quiere dejar de fumar pero quiere mantener la tendencia!<br \/>\nEste conjunto contiene el sistema de pods y 2 pods<\/div>\n<p>\u00a0<\/p>\n<div><\/div>\n<div>Gippro GP6 personalizaci\u00f3n dividida Dise\u00f1o ergon\u00f3mico del cigarrillo electr\u00f3nico, sin bordes ni esquinas afiladas, agarre suave con revestimiento de la marca de autos deportivos Ferrari, tanto protecci\u00f3n ambiental como valor nominal. Proceso de tratamiento de la superficie de la piel del beb\u00e9, dando una sensaci\u00f3n de piel similar a la de un beb\u00e9. Japan Smart Air El n\u00facleo de personalizaci\u00f3n din\u00e1mica mejora la suavidad 3 veces y reduce los problemas de fugas de aceite y aceite graso. La boquilla se adapta perfectamente a la forma de los labios y el proceso a nivel nanom\u00e9trico es seco y antibacteriano.<\/div>\n<div><\/div>\n<div><\/div>\n<div>\n<p>\ud83c\uddef\ud83c\uddf5 El \u00fanico en el mercado que obtiene cuarentena inofensiva de calidad alimentaria japonesa<br \/>\n\ud83c\uddef\ud83c\uddf5La \u00fanica glicerina natural del mercado<br \/>\n\ud83c\uddef\ud83c\uddf5 El \u00fanico propilenglicol de calidad alimentaria del mercado<br \/>\n\ud83c\uddef\ud83c\uddf5 La \u00fanica sal de nicotina org\u00e1nica del mercado<br \/>\n\ud83c\uddef\ud83c\uddf5 El \u00fanico proveedor japon\u00e9s Hasegawa Spice en el mercado<br \/>\n\ud83c\uddef\ud83c\uddf5 El \u00fanico mercado aprobado por el Ministerio de Salud, Trabajo y Bienestar<\/p>\n<h2>Especificaci\u00f3n:<\/h2>\n<ul>\n<li>Tama\u00f1o del cuerpo: 100.2mm * 25.5mm * 12mm<br \/>\nPeso corporal: 0,19 kg<br \/>\nCapacidad de la bater\u00eda: 400 mAh<br \/>\nTiempo de carga: minutos 70<br \/>\nVoltaje de la bater\u00eda: 3,7 V<br \/>\nCapacidad del nebulizador: 2,0 ml<br \/>\nContenido: 1 m\u00e1quina + 2 cartuchos<br \/>\nContiene sabor a bomba de humo: menta fresca 0 mg, pomelo mango 0 mg<\/li>\n<\/ul>\n<p>lista de equipaje:<\/p>\n<ul>\n<li>Caja de embalaje<br \/>\nCaja de sobres<br \/>\ngu\u00eda del usuario<br \/>\nPolo de bater\u00eda<br \/>\nNebulizador * 2<br \/>\nCable de datos USB<br \/>\ncertificado<\/li>\n<\/ul>\n<p><strong>Pod compatible: Pod Gippro GP6<\/strong><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gippro GP6 ingenio japon\u00e9s El \u00faltimo producto de Gippro GP6 es m\u00e1s popular en Jap\u00f3n. Su apariencia de moda hace que se convierta en una nueva tendencia entre los zurdos y existe una versi\u00f3n sin nicotina. \u00a1Est\u00e1 dise\u00f1ado para usted que quiere dejar de fumar pero quiere mantener la tendencia! Este conjunto contiene el sistema [&#8230;]\n","protected":false},"featured_media":337056,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2818],"product_tag":[],"class_list":["post-330214","product","type-product","status-publish","has-post-thumbnail","product_cat-hnb-tabaco-calentado","first","instock","sale","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product\/330214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/comments?post=330214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/media\/337056"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/media?parent=330214"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_brand?post=330214"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_cat?post=330214"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/es\/wp-json\/wp\/v2\/product_tag?post=330214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}