{"id":274650,"date":"2024-05-09T11:25:18","date_gmt":"2024-05-09T03:25:18","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/skwezed-ice-green-apple-menthol-2-2\/"},"modified":"2026-06-23T18:01:57","modified_gmt":"2026-06-23T10:01:57","slug":"skwezed-ice-green-apple-menthol-2","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/fr\/produit\/skwezed-ice-green-apple-menthol-2\/","title":{"rendered":"Jus de vape SKWEZED ICE Green Apple Menthol Nic Salt 30 ml"},"content":{"rendered":"<h2>E-jus au sel de pomme verte SKWEZED ICE<\/h2>\n<ul class=\"haut\">\n<li style=\"list-style-type: none\">\n<ul class=\"haut\">\n<li>Marque\u00a0:\u00a0SKWEZED<\/li>\n<li>Unit\u00e9\u00a0: d\u00e9finie<\/li>\n<li>Type\u00a0:\u00a0Vape Juice<\/li>\n<li>Poids net\u00a0: 45(g)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Les frais d&rsquo;exp\u00e9dition combin\u00e9s seront calcul\u00e9s automatiquement par le syst\u00e8me apr\u00e8s avoir choisi la destination d&rsquo;exp\u00e9dition lors de l&rsquo;\u00e9tape de paiement.<\/p>\n<h3>SKWEZED ICE Jus \u00e9lectronique sel de pomme verte INTRODUCTION<\/h3>\n<p><b>Le jus \u00e9lectronique au sel de pomme verte SKWEZED ICE<\/b>\u00a0a le go\u00fbt d&rsquo;une saveur de pomme verte croquante qui a repos\u00e9 sur une montagne de glace avec du sel de nicotine et peut \u00e9blouir vos papilles gustatives.<\/p>\n<p>Sels de nicotine\u00a0:\u00a0<span style=\"color: #ce0000\">Le e-liquide aux sels de nicotine est sp\u00e9cialement con\u00e7u pour les appareils bas\u00e9s sur des pods et autres configurations \u00e0 faible rendement\/haute r\u00e9sistance. Nic Salt n&rsquo;est pas recommand\u00e9 pour une utilisation avec les r\u00e9servoirs et appareils RDA ou Sub-ohm.<\/span><\/p>\n<p class=\"second-title\">Fonctionnalit\u00e9s<\/p>\n<p>\u2022 Pomme verte, saveur menthol\u00e9e<\/p>\n<p>\u2022 Bouteille Licorne potel\u00e9e de 30\u00a0mL<\/p>\n<p>\u2022\u00a0Casquette \u00e0 l&rsquo;\u00e9preuve des enfants<\/p>\n<p>\u2022\u00a050% VG<\/p>\n<p>\u2022 50%PG<\/p>\n<p>\u2022\u00a0Formulation de sels de nicotine<\/p>\n<p>\u2022\u00a0Con\u00e7u pour une consommation ultra faible et un syst\u00e8me bas\u00e9 sur un module<\/p>\n<p>\u2022\u00a0Fabriqu\u00e9 aux \u00c9tats-Unis<\/p>\n<p>\u2022\u00a0Disponible en 25\u00a0mg, 50mg<\/p>\n<div class=\"title\">SP\u00c9CIFICATIONS du jus \u00e9lectronique SKWEZED ICE Sel de pomme verte<\/div>\n<p>Taille de la bouteille\u00a0: 30\u00a0ml<\/p>\n<p>VG\/PG\u00a0: 50\/50<\/p>\n<p>Type de bouteille\u00a0: Licorne<\/p>\n<p>Force de la nicotine\u00a0: 25\u00a0mg, 50mg<\/p>\n<p>Introduction \u00e0 la saveur\u00a0: pomme verte, menthol<\/p>\n<div class=\"title\">LISTE DES PAQUETS de jus \u00e9lectronique au sel de pomme verte SKWEZED ICE<\/div>\n<p>Forfait comprenant 1 x e-jus SKWEZED ICE au sel de pomme verte<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E-jus au sel de pomme verte SKWEZED ICE Marque\u00a0:\u00a0SKWEZED Unit\u00e9\u00a0: d\u00e9finie Type\u00a0:\u00a0Vape Juice Poids net\u00a0: 45(g) Les frais d&rsquo;exp\u00e9dition combin\u00e9s seront calcul\u00e9s automatiquement par le syst\u00e8me apr\u00e8s avoir choisi la destination d&rsquo;exp\u00e9dition lors de l&rsquo;\u00e9tape de paiement. SKWEZED ICE Jus \u00e9lectronique sel de pomme verte INTRODUCTION Le jus \u00e9lectronique au sel de pomme verte SKWEZED [&#8230;]\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2640],"product_tag":[],"class_list":["post-274650","product","type-product","status-publish","product_cat-e-liquides","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product\/274650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/comments?post=274650"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/media?parent=274650"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_brand?post=274650"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_cat?post=274650"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_tag?post=274650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}