{"id":274728,"date":"2024-05-09T10:55:32","date_gmt":"2024-05-09T02:55:32","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/ripe-vapes-cafe-cinnamon-coffee-cake-2\/"},"modified":"2026-06-23T18:08:19","modified_gmt":"2026-06-23T10:08:19","slug":"ripe-vapes-cafe-cinnamon-coffee-cake","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/fr\/produit\/ripe-vapes-cafe-cinnamon-coffee-cake\/","title":{"rendered":"Jus de vape Ripe Vapes Cafe Cinnamon Coffee Cake 60 ml"},"content":{"rendered":"<h2>E-jus Ripe Vapes Caf\u00e9<\/h2>\n<ul class=\"haut\">\n<li>Marque\u00a0:\u00a0<b>Ripe Vapes<\/b><\/li>\n<li>Unit\u00e9\u00a0: d\u00e9finie<\/li>\n<li>Type\u00a0:\u00a0<b>Vape Juice<\/b><\/li>\n<li>Poids net\u00a0: 75(g)<\/li>\n<\/ul>\n<p>Les frais d&rsquo;exp\u00e9dition combin\u00e9s seront calcul\u00e9s automatiquement par le syst\u00e8me apr\u00e8s avoir choisi la destination d&rsquo;exp\u00e9dition lors de l&rsquo;\u00e9tape de paiement.<\/p>\n<div class=\"title\">Introduction du jus \u00e9lectronique Ripe Vapes Cafe<\/div>\n<p><b>Le jus \u00e9lectronique Ripe Vapes Cafe<\/b> est livr\u00e9 avec une grande quantit\u00e9 de 60\u00a0ml de jus de vape, il existe des concentrations de nicotine disponibles (3\u00a0mg, 6\u00a0mg et 12\u00a0mg) et partage une saveur similaire \u00e0 celle du g\u00e2teau au caf\u00e9 et \u00e0 la cannelle. Ripe Vapes remplit une bouteille de 60 ml de jus de vape d\u00e9licieux et classique. L&rsquo;amertume et la douceur sont bien \u00e9quilibr\u00e9es dans une seule bouteille. Que vous soyez amateur de desserts ou vapoteur exp\u00e9riment\u00e9, vous pourrez vous faire plaisir avec le E-juice Ripe Vapes Caf\u00e9. Il est temps de rendre votre vie \u00e9l\u00e9gante et color\u00e9e avec du jus de vape de haute qualit\u00e9.<\/p>\n<p class=\"second-title\">Fonctionnalit\u00e9s<\/p>\n<p>\u2022\u00a0Bouteille Chubby Gorilla de 60\u00a0ml<\/p>\n<p>\u2022\u00a075% VG<\/p>\n<p>\u2022 25%PG<\/p>\n<p>\u2022\u00a0Formulation de nicotine synth\u00e9tique<\/p>\n<p>\u2022\u00a0Fabriqu\u00e9 aux \u00c9tats-Unis<\/p>\n<p>\u2022\u00a0Nicotine disponible\u00a0: 3\u00a0mg, 6\u00a0mg, 12\u00a0mg<\/p>\n<div class=\"title\">Liste des paquets de jus \u00e9lectroniques Ripe Vapes Cafe<\/div>\n<p>Forfait comprenant 1 x jus \u00e9lectronique Ripe Vapes Cafe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E-jus Ripe Vapes Caf\u00e9 Marque\u00a0:\u00a0Ripe Vapes Unit\u00e9\u00a0: d\u00e9finie Type\u00a0:\u00a0Vape Juice Poids net\u00a0: 75(g) Les frais d&rsquo;exp\u00e9dition combin\u00e9s seront calcul\u00e9s automatiquement par le syst\u00e8me apr\u00e8s avoir choisi la destination d&rsquo;exp\u00e9dition lors de l&rsquo;\u00e9tape de paiement. Introduction du jus \u00e9lectronique Ripe Vapes Cafe Le jus \u00e9lectronique Ripe Vapes Cafe est livr\u00e9 avec une grande quantit\u00e9 de 60\u00a0ml [&#8230;]\n","protected":false},"featured_media":132545,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2640],"product_tag":[],"class_list":["post-274728","product","type-product","status-publish","has-post-thumbnail","product_cat-e-liquides","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product\/274728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/comments?post=274728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/media\/132545"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/media?parent=274728"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_brand?post=274728"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_cat?post=274728"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_tag?post=274728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}