{"id":274830,"date":"2024-05-08T17:40:11","date_gmt":"2024-05-08T09:40:11","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/mango-strawberry-dragonfruit-e-juice-2\/"},"modified":"2026-06-23T18:16:26","modified_gmt":"2026-06-23T10:16:26","slug":"mango-strawberry-dragonfruit-e-juice","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/fr\/produit\/mango-strawberry-dragonfruit-e-juice\/","title":{"rendered":"Mango Strawberry Dragonfruit E-Juice by Pod Juice 100 ml &#8211; Liquide de vape triple fruit exotique, nuages riches, disponible en plusieurs niveaux de nicotine"},"content":{"rendered":"<h2>Pod Juice E-jus Mangue Fraise Dragonfruit 100ml<\/h2>\n<ul class=\"haut\">\n<li>Marque\u00a0:\u00a0Pod Juice<\/li>\n<li>Unit\u00e9\u00a0: d\u00e9finie<\/li>\n<li>Type\u00a0:\u00a0Vape Juice<\/li>\n<li>Poids net\u00a0: 104(g)<\/li>\n<\/ul>\n<p>Les frais d&rsquo;exp\u00e9dition combin\u00e9s seront calcul\u00e9s automatiquement par le syst\u00e8me apr\u00e8s avoir choisi la destination d&rsquo;exp\u00e9dition lors de l&rsquo;\u00e9tape de paiement.<\/p>\n<div class=\"title\">Pod Juice Mangue Fraise Dragonfruit E-jus 100ml INTRODUCTION<\/div>\n<p>Le e-jus Pod Juice Mangue Fraise Dragonfruit est un produit d&rsquo;une contenance de 100 ml. Les saveurs se combinent avec les merveilleuses saveurs de mangue, de fraise et de fruit du dragon, vous permettant de go\u00fbter trois fruits diff\u00e9rents \u00e0 la fois. Il est \u00e9galement livr\u00e9 avec trois niveaux de nicotine diff\u00e9rents. Lorsque vous l&rsquo;inhalez, la saveur du fruit frais regorge de papilles gustatives, et son go\u00fbt agr\u00e9able vous rendra \u00e9galement inoubliable.<\/p>\n<p class=\"second-title\">Fonctionnalit\u00e9s<\/p>\n<p>\u2022 Mangue, fraise, fruit du dragon<\/p>\n<p>\u2022 Bouteille Licorne potel\u00e9e de 100\u00a0mL<\/p>\n<p>\u2022\u00a0Casquette \u00e0 l&rsquo;\u00e9preuve des enfants<\/p>\n<p>\u2022\u00a070% VG<\/p>\n<p>\u2022 30%PG<\/p>\n<p>\u2022\u00a0Fabriqu\u00e9 aux \u00c9tats-Unis<\/p>\n<p>\u2022\u00a0Disponible en 0\u00a0mg, 3\u00a0mg et 6\u00a0mg<\/p>\n<div class=\"title\">Pod Juice Mangue Fraise Dragonfruit E-juice 100ml SP\u00c9CIFICATION<\/div>\n<div class=\"sp\u00e9cification\">\n<div class=\"splist\"><em>Taille de la bouteille\u00a0:<\/em>100\u00a0ml<\/div>\n<div class=\"splist\"><em>Ratio de m\u00e9lange\u00a0:<\/em>70VG\/30PG<\/div>\n<div class=\"splist\"><em>Niveau de nicotine\u00a0:<\/em>0\u00a0mg, 3\u00a0mg, 6\u00a0mg<\/div>\n<div class=\"splist\"><em>Profil de saveur\u00a0: <\/em>Mangue, Fraise, Fruit du dragon<\/div>\n<\/div>\n<div class=\"title\">Pod Juice Mangue Fraise Dragonfruit E-juice 100ml LISTE DES COLIS<\/div>\n<p>Forfait comprenant 1 bouteille X Pod Juice E-jus mangue fraise dragonfruit <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pod Juice E-jus Mangue Fraise Dragonfruit 100ml Marque\u00a0:\u00a0Pod Juice Unit\u00e9\u00a0: d\u00e9finie Type\u00a0:\u00a0Vape Juice Poids net\u00a0: 104(g) Les frais d&rsquo;exp\u00e9dition combin\u00e9s seront calcul\u00e9s automatiquement par le syst\u00e8me apr\u00e8s avoir choisi la destination d&rsquo;exp\u00e9dition lors de l&rsquo;\u00e9tape de paiement. Pod Juice Mangue Fraise Dragonfruit E-jus 100ml INTRODUCTION Le e-jus Pod Juice Mangue Fraise Dragonfruit est un produit [&#8230;]\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2640],"product_tag":[],"class_list":["post-274830","product","type-product","status-publish","product_cat-e-liquides","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product\/274830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/comments?post=274830"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/media?parent=274830"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_brand?post=274830"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_cat?post=274830"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_tag?post=274830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}