{"id":274854,"date":"2024-05-08T17:28:22","date_gmt":"2024-05-08T09:28:22","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/pod-juice-salts-series-cotton-carnival-e-juice-2\/"},"modified":"2026-06-23T18:18:18","modified_gmt":"2026-06-23T10:18:18","slug":"pod-juice-salts-series-cotton-carnival-e-juice","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/fr\/produit\/pod-juice-salts-series-cotton-carnival-e-juice\/","title":{"rendered":"Pod Juice Salts Cotton Carnival E-Juice vente en gros 30 ml saveur de vanille rose framboise bleue"},"content":{"rendered":"<h2>Pod Juice Blue Razz Lemonade Freeze E-jus 100 ml<\/h2>\n<ul class=\"haut\">\n<li>Marque\u00a0:\u00a0Pod Juice<\/li>\n<li>Unit\u00e9\u00a0: d\u00e9finie<\/li>\n<li>Type\u00a0:\u00a0Vape Juice<\/li>\n<li>Poids net\u00a0: 104(g)<\/li>\n<\/ul>\n<p>Les frais d&rsquo;exp\u00e9dition combin\u00e9s seront calcul\u00e9s automatiquement par le syst\u00e8me apr\u00e8s avoir choisi la destination d&rsquo;exp\u00e9dition lors de l&rsquo;\u00e9tape de paiement.<\/p>\n<div class=\"title\">Pod Juice Blue Razz Lemonade Freeze E-jus 100ml INTRODUCTION<\/div>\n<p>Le jus \u00e9lectronique Pod Juice Blue Razz Lemonade Freeze, rien que par son nom, est d\u00e9j\u00e0 assez tentant. Le grand verre est charg\u00e9 de gla\u00e7ons brillants et translucides, rempli de limonade cristalline et termin\u00e9 par une garniture de framboises bleues douces et charnues, la boisson glac\u00e9e aux fruits rafra\u00eechissante se compl\u00e8te instantan\u00e9ment. L&rsquo;\u00e9norme capacit\u00e9 de jus \u00e9lectronique de 100\u00a0ml combin\u00e9e aux trois concentrations de nicotine en option vous fera s\u00fbrement tomber amoureux du Blue Razz Lemonade Freeze.<\/p>\n<p class=\"second-title\">Fonctionnalit\u00e9s<\/p>\n<p>\u2022 Framboises bleues, limonade, menthol<\/p>\n<p>\u2022 Bouteille Licorne potel\u00e9e de 100\u00a0mL<\/p>\n<p>\u2022\u00a0Casquette \u00e0 l&rsquo;\u00e9preuve des enfants<\/p>\n<p>\u2022\u00a070% VG<\/p>\n<p>\u2022 30%PG<\/p>\n<p>\u2022\u00a0Fabriqu\u00e9 aux \u00c9tats-Unis<\/p>\n<p>\u2022\u00a0Disponible en 0\u00a0mg, 3\u00a0mg et 6\u00a0mg<\/p>\n<div class=\"title\">Pod Juice Blue Razz Lemonade Freeze E-jus 100ml SP\u00c9CIFICATION<\/div>\n<div class=\"sp\u00e9cification\">\n<div class=\"splist\"><em>Taille de la bouteille\u00a0:<\/em>100\u00a0ml<\/div>\n<div class=\"splist\"><em>Ratio de m\u00e9lange\u00a0:<\/em>70VG\/30PG<\/div>\n<div class=\"splist\"><em>Niveau de nicotine\u00a0:<\/em>0\u00a0mg, 3\u00a0mg, 6\u00a0mg<\/div>\n<div class=\"splist\"><em>Profil de saveur\u00a0: <\/em>Framboises bleues, limonade, menthol<\/div>\n<\/div>\n<div class=\"title\">Pod Juice Blue Razz Lemonade Freeze E-jus 100 ml LISTE DES COLIS<\/div>\n<p>Forfait comprenant 1 bouteille X Pod Juice Blue Razz Lemonade Freeze E-juice <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pod Juice Salts Cotton Carnival E-Juice Wholesale propose un doux m\u00e9lange d&rsquo;ar\u00f4mes de framboise bleue et de vanille rose, parfait pour les amateurs de saveurs \u00e0 la recherche de 30\u00a0ml de sel de qualit\u00e9 sup\u00e9rieure.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2640],"product_tag":[],"class_list":["post-274854","product","type-product","status-publish","product_cat-e-liquides","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product\/274854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/comments?post=274854"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/media?parent=274854"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_brand?post=274854"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_cat?post=274854"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_tag?post=274854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}