{"id":275040,"date":"2024-05-07T11:37:34","date_gmt":"2024-05-07T03:37:34","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/tropical-passion-orange-guava-vape-juice-naked-100-hawaiian-pog-e-juice-60ml-2\/"},"modified":"2026-06-23T18:33:04","modified_gmt":"2026-06-23T10:33:04","slug":"tropical-passion-orange-guava-vape-juice-naked-100-hawaiian-pog-e-juice-60ml","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/fr\/produit\/tropical-passion-orange-guava-vape-juice-naked-100-hawaiian-pog-e-juice-60ml\/","title":{"rendered":"Tropical Passion Orange Guava Vape Juice &#8211; Naked 100 E-jus POG hawa\u00efen 60 ml"},"content":{"rendered":"<h2>E-jus POG hawa\u00efen 100 nu 60 ml<\/h2>\n<ul class=\"haut\">\n<li>\n<ul class=\"haut\">\n<li>Marque\u00a0:\u00a0Naked 100<\/li>\n<li>Unit\u00e9\u00a0: d\u00e9finie<\/li>\n<li>Type\u00a0:\u00a0Vape Juice<\/li>\n<li>Poids net\u00a0: 75(g)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Les frais d&rsquo;exp\u00e9dition combin\u00e9s seront calcul\u00e9s automatiquement par le syst\u00e8me apr\u00e8s avoir choisi la destination d&rsquo;exp\u00e9dition lors de l&rsquo;\u00e9tape de paiement.<\/p>\n<div class=\"title\">Introduction du jus \u00e9lectronique POG hawa\u00efen 100 nu<\/div>\n<p>Naked 100 Hawaiian POG\u00a0est un produit e-liquide haut de gamme qui offre un d\u00e9licieux m\u00e9lange de saveurs tropicales. Avec un ratio 70\/30 VG\/PG, cet e-liquide est parfait pour produire de gros nuages \u200b\u200bde vapeur tout en offrant un coup de gorge doux. Le format du flacon de 60 ml est pratique et durable. Le profil aromatique du POG hawa\u00efen pr\u00e9sente une combinaison unique de fruit de la passion, d&rsquo;orange et de goyave parfaitement \u00e9quilibr\u00e9e pour cr\u00e9er une exp\u00e9rience de vape all\u00e9chante. Ce jus \u00e9lectronique est disponible en dosages de nicotine de 0 mg, 3 mg et 6 mg, ce qui le rend adapt\u00e9 aux vapoteurs d\u00e9butants et exp\u00e9riment\u00e9s. Le jus \u00e9lectronique POG hawa\u00efen Naked 100 60 ml est un incontournable pour tous ceux qui aiment les saveurs fruit\u00e9es et exotiques des jus \u00e9lectroniques.<\/p>\n<p>\u00a0<\/p>\n<p class=\"second-title\">Fonctionnalit\u00e9s<\/p>\n<p>\u2022 Bouteille Licorne potel\u00e9e de 60\u00a0mL<\/p>\n<p>\u2022\u00a065% VG<\/p>\n<p>\u2022 35%PG<\/p>\n<p>\u2022\u00a0Casquette \u00e0 l&rsquo;\u00e9preuve des enfants<\/p>\n<p>\u2022\u00a0Fabriqu\u00e9 aux \u00c9tats-Unis<\/p>\n<p>\u2022\u00a0Nicotine disponible\u00a0: 0\u00a0mg, 3\u00a0mg, 6\u00a0mg, 12\u00a0mg<\/p>\n<div class=\"title\">SP\u00c9CIFICATION du jus \u00e9lectronique POG hawa\u00efen 100 nu<\/div>\n<p>Taille de la bouteille\u00a0: 60\u00a0ml<\/p>\n<p>VG\/PG\u00a0: 35\/65<\/p>\n<p>Type de bouteille\u00a0: Licorne<\/p>\n<p>Niveau de nicotine\u00a0: 0\u00a0mg, 3\u00a0mg, 6\u00a0mg, 12\u00a0mg<\/p>\n<p>Profil de saveur\u00a0: Fruit de la passion, orange, goyave<\/p>\n<div class=\"title\">LISTE DE PAQUETS de jus \u00e9lectronique POG hawa\u00efen 100 nu<\/div>\n<p>Forfait comprenant\u00a01\u00a0jus \u00e9lectronique POG hawa\u00efen Naked 100<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E-jus POG hawa\u00efen 100 nu 60 ml Marque\u00a0:\u00a0Naked 100 Unit\u00e9\u00a0: d\u00e9finie Type\u00a0:\u00a0Vape Juice Poids net\u00a0: 75(g) Les frais d&rsquo;exp\u00e9dition combin\u00e9s seront calcul\u00e9s automatiquement par le syst\u00e8me apr\u00e8s avoir choisi la destination d&rsquo;exp\u00e9dition lors de l&rsquo;\u00e9tape de paiement. Introduction du jus \u00e9lectronique POG hawa\u00efen 100 nu Naked 100 Hawaiian POG\u00a0est un produit e-liquide haut de gamme [&#8230;]\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2640],"product_tag":[],"class_list":["post-275040","product","type-product","status-publish","product_cat-e-liquides","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product\/275040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/comments?post=275040"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/media?parent=275040"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_brand?post=275040"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_cat?post=275040"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_tag?post=275040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}