{"id":277694,"date":"2023-11-14T18:23:53","date_gmt":"2023-11-14T10:23:53","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/smok-novo-bar-al9000-9000-puffs-disposable-vape-wholesale-2\/"},"modified":"2026-06-23T21:28:46","modified_gmt":"2026-06-23T13:28:46","slug":"smok-novo-bar-al9000-9000-puffs-disposable-vape-wholesale","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/fr\/produit\/smok-novo-bar-al9000-9000-puffs-disposable-vape-wholesale\/","title":{"rendered":"SMOK Novo Bar AL9000 9000 bouff\u00e9es Vape jetable vente en gros construction rechargeable durable"},"content":{"rendered":"<h2>Vapeur jetable SMOK Novo Bar AL9000<\/h2>\n<ul class=\"haut\">\n<li>\n<ul class=\"haut\">\n<li>Marque\u00a0:\u00a0<b>SMOK<\/b><b><\/b><\/li>\n<li>Unit\u00e9\u00a0: d\u00e9finie<\/li>\n<li>Type\u00a0:\u00a0<b>Vapeur jetable<\/b><\/li>\n<li>Poids net\u00a0: 90(g)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Les frais d&rsquo;exp\u00e9dition combin\u00e9s seront calcul\u00e9s automatiquement par le syst\u00e8me apr\u00e8s avoir choisi la destination d&rsquo;exp\u00e9dition lors de l&rsquo;\u00e9tape de paiement.<\/p>\n<div class=\"title\">SMOK Novo Bar AL9000 Vape jetable INTRODUCTION<\/div>\n<p><b>Le vapoteur jetable SMOK Novo Bar AL9000<\/b>\u00a0est \u00e9quip\u00e9 d&rsquo;un e-liquide pr\u00e9rempli de 15\u00a0ml et d&rsquo;une batterie rechargeable de 800\u00a0mAh, qui peut permettre de vapoter jusqu&rsquo;\u00e0 des bouff\u00e9es de 9000. La concentration de 50 mg de nicotine peut vous offrir une exp\u00e9rience de vapotage id\u00e9ale et exacte. La finition de couleur contrast\u00e9e et son cadre en forme de caisson apportent un design lumineux et harmonieux. Avec sa puissance maximale 17W et une bobine maill\u00e9e int\u00e9gr\u00e9e, il peut am\u00e9liorer la saveur originale via un commutateur de d\u00e9bit d&rsquo;air par le bas.<\/p>\n<p class=\"second-title\">Fonctionnalit\u00e9s<\/p>\n<p>\u2022 Taille\u00a0: 45.8*27*83.9\u00a0mm<\/p>\n<p>\u2022\u00a015\u00a0ml de jus de vape pr\u00e9rempli<\/p>\n<p>\u2022\u00a05\u00a0% (50\u00a0mg) de sel de nicotine<\/p>\n<p>\u2022\u00a0Batterie rechargeable de 800\u00a0mAh<\/p>\n<p>\u2022 Port USB-C<\/p>\n<p>\u2022 Environ\u00a0bouff\u00e9es 9000<\/p>\n<p>\u2022 Bobine de maillage<\/p>\n<p>\u2022 Activ\u00e9 par tirage<\/p>\n<p>\u2022 Indicateurs de liquide et de batterie<\/p>\n<p>\u2022\u00a0Puissance maximale du 17W<\/p>\n<p>\u2022 Courant de charge 0,77A<\/p>\n<p>\u2022\u00a0Commutateur de d\u00e9bit d&rsquo;air<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SMOK Novo Bar AL9000 fournit des bouff\u00e9es 9000, offrant une construction durable et rechargeable pour des exp\u00e9riences de vapotage de longue dur\u00e9e.<\/p>\n","protected":false},"featured_media":126475,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2637,2705,2636],"product_tag":[3431],"class_list":["post-277694","product","type-product","status-publish","has-post-thumbnail","product_cat-jetable","product_cat-vapes-jetables-9000-bouffees","product_cat-differentes-bouffees-de-vapes-jetables","product_tag-meilleure-vape-jetable-en-vente","first","instock","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":{"1000":14,"10000":12,"50000":10},"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":100,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product\/277694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/comments?post=277694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/media\/126475"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/media?parent=277694"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_brand?post=277694"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_cat?post=277694"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_tag?post=277694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}