{"id":329450,"date":"2021-06-16T16:39:13","date_gmt":"2021-06-16T08:39:13","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/reepuff-glow-1500-puffs-disposable-pod-device-2\/"},"modified":"2026-06-24T09:48:14","modified_gmt":"2026-06-24T01:48:14","slug":"reepuff-glow-1500-puffs-disposable-pod-device","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/fr\/produit\/reepuff-glow-1500-puffs-disposable-pod-device\/","title":{"rendered":"Conception compacte de vapeur douce en gros de dispositif jetable de cosse de souffles de Reepuff Glow 1500"},"content":{"rendered":"<p>Le r\u00e9servoir contient 5 ml d&rsquo;e-liquide et dure environ des bouff\u00e9es 1500. C\u2019est suffisant pour vous permettre de vapoter aussi longtemps que vous le souhaitez. La r\u00e9sistance de la bobine est de 1,0 ohm et est con\u00e7ue pour reproduire la sensation de fumer. De plus, le r\u00e9servoir int\u00e9gr\u00e9 <strong>Reepuff Glow<\/strong> dispose d&rsquo;un m\u00e9canisme pull &amp; play unique, qui peut fournir un go\u00fbt r\u00e9el et la s\u00e9curit\u00e9 de l&rsquo;e-liquide interne. L&#8217;embout ergonomique est confortable \u00e0 vapoter et un design totalement transparent vous permet de v\u00e9rifier \u00e0 tout moment la consommation actuelle de jus \u00e9lectronique. De plus, il s&rsquo;allume comme un b\u00e2ton lumineux en 7 couleurs diff\u00e9rentes, il est vraiment tendance, <strong>Reepuff Glow<\/strong> offre une exp\u00e9rience de vapotage satisfaisante qui reproduit fid\u00e8lement la sensation d&rsquo;inhaler une cigarette.<\/p>\n<p><strong>Sp\u00e9cification\u00a0:<\/strong><br \/>\n\u2022 Dispositif de syst\u00e8me de dosettes jetables avec conception brevet\u00e9e Pull and Play<br \/>\n\u2022 Il s&rsquo;allume comme un b\u00e2ton lumineux en 7 couleurs diff\u00e9rentes<br \/>\n\u2022 Pod transparent pour v\u00e9rifier facilement l&rsquo;e-liquide<br \/>\n\u2022 SOUFFL\u00c9ES 1500<br \/>\n\u2022 Rechargeable<br \/>\n\u2022 Taille\u00a0: 18*105\u00a0mm<br \/>\n\u2022 Capacit\u00e9 de la batterie\u00a0: 650 mAh<br \/>\n\u2022 Tension de sortie\u00a0: 3,5\u00a0V<br \/>\n\u2022 Capacit\u00e9 du jus \u00e9lectronique\u00a0: 5,0\u00a0ml<br \/>\n\u2022 R\u00e9sistance de la bobine\u00a0:\u00a01,0\u00a0\u03a9<br \/>\n\u2022 Mat\u00e9riau\u00a0: Acier inoxydable et PCTG<br \/>\n\u2022\u00a0Saveurs d\u00e9licieuses 10 et excellent tirage MTL<\/p>\n<p>Pour en savoir plus, veuillez consulter YouTube\u00a0:<\/p>\n<p><iframe loading=\"lazy\" title=\"2021 BEST FLAVOR  DISPOSABLE POD  DEVICE ? ------Reepuff glow 1500 puffs disposable pod kit\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/XXuQsOuzWjc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le dispositif \u00e0 dosettes jetables Reepuff Glow 1500 Puffs offre une vapeur douce avec un design compact, ce qui en fait un choix id\u00e9al pour les vapoteurs \u00e0 la recherche de portabilit\u00e9 et de performances.<\/p>\n","protected":false},"featured_media":328707,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2637,2659,2636],"product_tag":[3431],"class_list":["post-329450","product","type-product","status-publish","has-post-thumbnail","product_cat-jetable","product_cat-vapes-jetables-1500-bouffees","product_cat-differentes-bouffees-de-vapes-jetables","product_tag-meilleure-vape-jetable-en-vente","wcpv_product_vendors-reewape","first","instock","shipping-taxable","product-type-simple"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product\/329450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/comments?post=329450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/media\/328707"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/media?parent=329450"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_brand?post=329450"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_cat?post=329450"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_tag?post=329450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}