{"id":330182,"date":"2020-11-11T12:23:47","date_gmt":"2020-11-11T04:23:47","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/relx-classic-starter-kit-with-1-device-and-2-pods-2\/"},"modified":"2026-06-24T14:28:55","modified_gmt":"2026-06-24T06:28:55","slug":"relx-classic-starter-kit-with-1-device-and-2-pods","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/fr\/produit\/relx-classic-starter-kit-with-1-device-and-2-pods\/","title":{"rendered":"KIT RELX CLASSIC STARTER avec 1 appareil et 2 pods"},"content":{"rendered":"<div>Pr\u00e9sentation de base du KIT RELX CLASSIC STARTER\u00a0:<\/div>\n<div>1. Le b\u00e2ton de cigarette est en m\u00e9tal, antichute et r\u00e9sistant \u00e0 l&rsquo;huile.<\/div>\n<div>2. Le pod a un contact m\u00e9tallique. La tige et la nacelle sont coll\u00e9es ensemble par un aimant. Apr\u00e8s la combinaison, vous pourrez profiter du go\u00fbt de la vape.<\/div>\n<div>3. Les dosettes RELX ont une v\u00e9ritable sensation de gorge de cigarette.<\/div>\n<div>4. Le vrai go\u00fbt de fum\u00e9e et l&rsquo;absence de goudron \u00e0 l&rsquo;int\u00e9rieur sont beaucoup plus sains.<\/div>\n<div>5. Un pod peut fumer environ des fois 500 \u00e0 600. Apr\u00e8s avoir fum\u00e9, vous pouvez directement jeter et remplacer le suivant.<\/div>\n<div>6. Compl\u00e8tement charg\u00e9 en environ 45\u00a0minutes\u00a0:<\/div>\n<ul>\n<li>Tabagisme normal\u00a0: le voyant reste allum\u00e9 puis s&rsquo;\u00e9teint lentement<\/li>\n<li>Batterie faible\u00a0: les lumi\u00e8res clignoteront en continu pendant que vous fumez<\/li>\n<li>Lors du chargement\u00a0: le voyant blanc est allum\u00e9<\/li>\n<li>Charge termin\u00e9e\u00a0: lumi\u00e8re \u00e9teinte<\/li>\n<\/ul>\n<div><\/div>\n<div><b>Pr\u00e9cautions\u00a0:<\/b><\/div>\n<div>Les utilisateurs doivent s&rsquo;assurer qu&rsquo;ils ne sont pas expos\u00e9s \u00e0 l&rsquo;eau pendant l&rsquo;utilisation pour \u00e9viter d&rsquo;endommager la machine.<\/div>\n<div><\/div>\n<div><b>Sp\u00e9cifications\u00a0:<\/b><\/div>\n<div>Capacit\u00e9 de la batterie\u00a0: 350 mAh<\/div>\n<div>Temps de charge\u00a0:\u00a0minutes 45-60<\/div>\n<div>Nombre de bouff\u00e9es disponibles une fois compl\u00e8tement charg\u00e9e\u00a0: 250 ~ 300<\/div>\n<div>Poids de la tige du syst\u00e8me Pod\u00a0: 17\u00a0g<\/div>\n<p>Diff\u00e9rentes couleurs avec diff\u00e9rents pods\u00a0:<\/p>\n<p><b>Noir, Rouge, Or Rose, Gris Espace, Bleu Marine sont livr\u00e9s avec\u00a0: Menthe 5\u00a0% et Tabac 5\u00a0%<\/b><\/p>\n<p><b>Solar Eclipse, Sunset Glow, Turquoise Blue, Mystic Aurora, Radiant Nebula sont livr\u00e9s avec Mung Bean 3\u00a0% et Ice Watermelon<\/b><\/p>\n<div>Applicable \u00e0\u00a0: uniquement applicable aux pods Relx Classic et Universal\u00a0: pod Vapemoho, pod Huanxi, pod fuji vape, pod giko vape, pod lumineux Make Herbal, pod WDG, pod Veex, pod SP2S.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00e9sentation de base du KIT RELX CLASSIC STARTER\u00a0: 1. Le b\u00e2ton de cigarette est en m\u00e9tal, antichute et r\u00e9sistant \u00e0 l&rsquo;huile. 2. Le pod a un contact m\u00e9tallique. La tige et la nacelle sont coll\u00e9es ensemble par un aimant. Apr\u00e8s la combinaison, vous pourrez profiter du go\u00fbt de la vape. 3. Les dosettes RELX ont [&#8230;]\n","protected":false},"featured_media":336526,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2648],"product_tag":[],"class_list":["post-330182","product","type-product","status-publish","has-post-thumbnail","product_cat-kits-de-demarrage","first","instock","sale","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product\/330182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/comments?post=330182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/media\/336526"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/media?parent=330182"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_brand?post=330182"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_cat?post=330182"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/fr\/wp-json\/wp\/v2\/product_tag?post=330182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}