{"id":274677,"date":"2024-05-09T11:17:34","date_gmt":"2024-05-09T03:17:34","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/skwezed-green-apple-2\/"},"modified":"2026-06-23T18:04:13","modified_gmt":"2026-06-23T10:04:13","slug":"skwezed-green-apple","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/it\/prodotto\/skwezed-green-apple\/","title":{"rendered":"SKWEZED Green Apple Nic Salt Succo Vape 30ml"},"content":{"rendered":"<h2>E-juice al sale di mela verde SKZEZED<\/h2>\n<ul class=\"top\">\n<li style=\"list-style-type: none\">\n<ul class=\"top\">\n<li>Marchio: SKWEZED<\/li>\n<li>Unit\u00e0: imposta<\/li>\n<li>Tipo: Vape Juice<\/li>\n<li>Peso netto: 45(g)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Il costo di spedizione combinato verr\u00e0 calcolato automaticamente dal sistema dopo aver scelto la destinazione della spedizione nella fase di pagamento.<\/p>\n<div class=\"title\">INTRODUZIONE all&#8217;e-juice al sale di mela verde SKWEZED<\/div>\n<p><b>L&#8217;e-juice al sale di mela verde SKWEZED<\/b>\u00a0porta un sapore frizzante e naturale di mela verde con una miscela di sale di nicotina, lasciandoti sprofondare in nuvole di naturale dolcezza e fruttata durante l&#8217;inalazione.<\/p>\n<p>Sali di nicotina:\u00a0<span style=\"color: #ce0000\">L&#8217;e-liquid di sale di nicotina \u00e8 progettato specificamente per dispositivi basati su Pod e altre configurazioni a basso rendimento\/alta resistenza. Nic Salt non \u00e8 consigliato per l&#8217;uso con serbatoi e dispositivi RDA o Sub-ohm.<\/span><\/p>\n<p class=\"second-title\">Caratteristiche<\/p>\n<p>\u2022 Gusto Mela Verde<\/p>\n<p>\u2022 Bottiglia di unicorno paffuto da 30 ml<\/p>\n<p>\u2022 Cappellino resistente ai bambini<\/p>\n<p>\u2022 50% VG<\/p>\n<p>\u2022 50%PG<\/p>\n<p>\u2022 Formulazione di sali di nicotina<\/p>\n<p>\u2022 Realizzato per un sistema a wattaggio estremamente basso e basato su pod<\/p>\n<p>\u2022 Prodotto negli Stati Uniti<\/p>\n<p>\u2022 Disponibile in 25 mg, 50mg<\/p>\n<div class=\"title\">SPECIFICHE E-juice al sale di mela verde SKWEZED<\/div>\n<p>Formato della bottiglia: 30 ml<\/p>\n<p>VG\/PG: 50\/50<\/p>\n<p>Tipo di bottiglia: Unicorno<\/p>\n<p>Concentrazione di nicotina: 25 mg, 50mg<\/p>\n<p>Introduzione al gusto: mela verde<\/p>\n<div class=\"title\">ELENCO PACCHETTI E-juice al sale di mela verde SKWEZED<\/div>\n<p>1 x E-juice al sale di mela verde SKWEZED<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E-juice al sale di mela verde SKZEZED Marchio: SKWEZED Unit\u00e0: imposta Tipo: Vape Juice Peso netto: 45(g) Il costo di spedizione combinato verr\u00e0 calcolato automaticamente dal sistema dopo aver scelto la destinazione della spedizione nella fase di pagamento. INTRODUZIONE all&#8217;e-juice al sale di mela verde SKWEZED L&#8217;e-juice al sale di mela verde SKWEZED\u00a0porta un sapore [&#8230;]\n","protected":false},"featured_media":132581,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2904],"product_tag":[],"class_list":["post-274677","product","type-product","status-publish","has-post-thumbnail","product_cat-e-liquidi","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/it\/wp-json\/wp\/v2\/product\/274677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/it\/wp-json\/wp\/v2\/comments?post=274677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/it\/wp-json\/wp\/v2\/media\/132581"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/it\/wp-json\/wp\/v2\/media?parent=274677"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/it\/wp-json\/wp\/v2\/product_brand?post=274677"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/it\/wp-json\/wp\/v2\/product_cat?post=274677"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/it\/wp-json\/wp\/v2\/product_tag?post=274677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}