{"id":275073,"date":"2024-05-07T11:30:07","date_gmt":"2024-05-07T03:30:07","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/cool-mint-blast-vape-juice-2\/"},"modified":"2026-06-23T18:35:48","modified_gmt":"2026-06-23T10:35:48","slug":"cool-mint-blast-vape-juice","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/it\/prodotto\/cool-mint-blast-vape-juice\/","title":{"rendered":"Cool Mint Blast Vape Juice &#8211; Twist Mint No.1 E-juice 60ml"},"content":{"rendered":"<h2>E-juice Twist Mint No.1<\/h2>\n<ul class=\"top\">\n<li style=\"list-style-type: none\">\n<ul class=\"top\">\n<li>Marchio:\u00a0<b>Twist<\/b><\/li>\n<li>Unit\u00e0: imposta<\/li>\n<li>Tipo:\u00a0<b>Vape Juice<\/b><\/li>\n<li>Peso netto: 105(g)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Il costo di spedizione combinato verr\u00e0 calcolato automaticamente dal sistema dopo aver scelto la destinazione della spedizione nella fase di pagamento.<\/p>\n<div class=\"title\">INTRODUZIONE all&#8217;e-juice Twist Mint No.1<\/div>\n<p><b>Twist Mint No.1 E-juice<\/b>\u00a0ti permette di immergerti nell&#8217;abbraccio allettante della menta ghiacciata, dove ogni inspirazione ti trasporta in un&#8217;oasi baciata dal gelo. Con una miscela meticolosamente realizzata, questo e-juice offre un&#8217;esplosione di pura euforia di menta, che ricorda una vivace brezza di montagna. Le note tonificanti della menta verde e della menta piperita danzano sul tuo palato, creando una fusione armoniosa che \u00e8 allo stesso tempo rinfrescante e soddisfacente. Che tu sia un vaper esperto o un nuovo arrivato.<\/p>\n<p class=\"second-title\">Caratteristiche<\/p>\n<p>\u2022 Bottiglia di unicorno da 60 ml*2<\/p>\n<p>\u2022 Cappellino resistente ai bambini<\/p>\n<p>\u2022 70% VG<\/p>\n<p>\u2022 30% PG<\/p>\n<p>\u2022 Formulazione sintetica di nicotina<\/p>\n<p>\u2022 Prodotto negli Stati Uniti<\/p>\n<p>\u2022 Disponibile in 3 mg, 6 mg<\/p>\n<div class=\"title\">ELENCO PACCHETTI E-juice Twist Mint No.1<\/div>\n<p>1 * E-juice Twist Mint No.1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E-juice Twist Mint No.1 Marchio:\u00a0Twist Unit\u00e0: imposta Tipo:\u00a0Vape Juice Peso netto: 105(g) Il costo di spedizione combinato verr\u00e0 calcolato automaticamente dal sistema dopo aver scelto la destinazione della spedizione nella fase di pagamento. INTRODUZIONE all&#8217;e-juice Twist Mint No.1 Twist Mint No.1 E-juice\u00a0ti permette di immergerti nell&#8217;abbraccio allettante della menta ghiacciata, dove ogni inspirazione ti trasporta [&#8230;]\n","protected":false},"featured_media":339767,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2904],"product_tag":[],"class_list":["post-275073","product","type-product","status-publish","has-post-thumbnail","product_cat-e-liquidi","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/it\/wp-json\/wp\/v2\/product\/275073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/it\/wp-json\/wp\/v2\/comments?post=275073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/it\/wp-json\/wp\/v2\/media\/339767"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/it\/wp-json\/wp\/v2\/media?parent=275073"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/it\/wp-json\/wp\/v2\/product_brand?post=275073"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/it\/wp-json\/wp\/v2\/product_cat?post=275073"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/it\/wp-json\/wp\/v2\/product_tag?post=275073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}