{"id":274684,"date":"2024-05-09T11:12:23","date_gmt":"2024-05-09T03:12:23","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/skwezed-ice-watermelon-mint-2\/"},"modified":"2026-06-23T18:04:33","modified_gmt":"2026-06-23T10:04:33","slug":"skwezed-ice-watermelon-mint","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/pt\/produto\/skwezed-ice-watermelon-mint\/","title":{"rendered":"Suco Vape SKWEZED ICE Watermelon Mint Flavor 100ml"},"content":{"rendered":"<h2>SKWEZED ICE E-suco de melancia 100ml<\/h2>\n<ul class=\"top\">\n<li>Marca:\u00a0<b>SKWEZED<\/b><\/li>\n<li>Unidade: conjunto<\/li>\n<li>Tipo:\u00a0<b>Suco Vape<\/b><\/li>\n<li>Peso l\u00edquido: 100(g)<\/li>\n<\/ul>\n<p>O custo combinado do frete ser\u00e1 calculado automaticamente pelo sistema ap\u00f3s voc\u00ea escolher o destino do frete na etapa de finaliza\u00e7\u00e3o da compra.<\/p>\n<div class=\"title\">SKWEZED ICE Melancia E-suco 100ml INTRODU\u00c7\u00c3O<\/div>\n<p>O suco eletr\u00f4nico de melancia SKWEZED ICE tem tr\u00eas n\u00edveis de nicotina para voc\u00ea escolher e tamb\u00e9m preenche uma garrafa completa de suco eletr\u00f4nico 100ml. A partir do momento em que voc\u00ea inala este delicioso suco eletr\u00f4nico de melancia gelada, voc\u00ea se lembrar\u00e1 dos prados perfumados e do sol e do c\u00e9u quente e puro do ver\u00e3o. Ao contr\u00e1rio de outro suco eletr\u00f4nico com sabor de melancia, o SKWEZED ICE Watermelon tamb\u00e9m tem uma mistura de menta fresca no suco eletr\u00f4nico para proporcionar uma experi\u00eancia vaping, como provar uma melancia gelada. Ao inspirar, o rico sabor da melancia traz o m\u00e1ximo conforto e, ao expirar, o frescor da menta se mistura com a do\u00e7ura da melancia madura. Trazendo a voc\u00ea o prazer \u00fanico do sabor residual, \u00e9 uma \u00f3tima op\u00e7\u00e3o de vaping que voc\u00ea nunca pode perder no ver\u00e3o.<\/p>\n<div class=\"title\">SKWEZED ICE Melancia E-suco 100ml ESPECIFICA\u00c7\u00d5ES<\/div>\n<div class=\"especifica\u00e7\u00e3o\">\n<div class=\"splist\"><em>Tamanho da garrafa:<\/em>100ml<\/div>\n<div class=\"splist\"><em>Combina\u00e7\u00e3o de propor\u00e7\u00e3o:<\/em>70VG\/30PG<\/div>\n<div class=\"splist\"><em>N\u00edvel de nicotina:<\/em>0mg, 3mg, 6mg<\/div>\n<div class=\"splist\"><em>Perfil de sabor:<\/em>Melancia, Mentol<\/div>\n<\/div>\n<div class=\"title\">SKWEZED ICE Melancia E-suco 100ml LISTA DE PACOTES<\/div>\n<p>1 garrafa X suco eletr\u00f4nico de melancia SKWEZED ICE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SKWEZED ICE E-suco de melancia 100ml Marca:\u00a0SKWEZED Unidade: conjunto Tipo:\u00a0Suco Vape Peso l\u00edquido: 100(g) O custo combinado do frete ser\u00e1 calculado automaticamente pelo sistema ap\u00f3s voc\u00ea escolher o destino do frete na etapa de finaliza\u00e7\u00e3o da compra. SKWEZED ICE Melancia E-suco 100ml INTRODU\u00c7\u00c3O O suco eletr\u00f4nico de melancia SKWEZED ICE tem tr\u00eas n\u00edveis de nicotina [&#8230;]\n","protected":false},"featured_media":132571,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2992],"product_tag":[],"class_list":["post-274684","product","type-product","status-publish","has-post-thumbnail","product_cat-liquidos-para-cigarros-eletronicos","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product\/274684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/comments?post=274684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/media\/132571"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/media?parent=274684"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_brand?post=274684"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_cat?post=274684"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_tag?post=274684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}