{"id":274852,"date":"2024-05-08T17:32:55","date_gmt":"2024-05-08T09:32:55","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/pod-juice-golden-custard-e-juice-2\/"},"modified":"2026-06-23T18:17:53","modified_gmt":"2026-06-23T10:17:53","slug":"pod-juice-golden-custard-e-juice","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/pt\/produto\/pod-juice-golden-custard-e-juice\/","title":{"rendered":"Pod Juice Golden Custard E-Juice 100ml &#8211; Vanilla, Custard, and Golden Tobacco Blend"},"content":{"rendered":"<h2>Pod Juice Golden Custard E-suco 100ml<\/h2>\n<ul class=\"top\">\n<li>Marca:\u00a0Suco de vagem<\/li>\n<li>Unidade: conjunto<\/li>\n<li>Tipo: Suco Vape<\/li>\n<li>Peso l\u00edquido: 104(g)<\/li>\n<\/ul>\n<p>O custo combinado do frete ser\u00e1 calculado automaticamente pelo sistema ap\u00f3s voc\u00ea escolher o destino do frete na etapa de finaliza\u00e7\u00e3o da compra.<\/p>\n<div class=\"title\">Pod Juice Golden Custard E-juice 100ml INTRODU\u00c7\u00c3O<\/div>\n<p>Se voc\u00ea adora a experi\u00eancia de vaporiza\u00e7\u00e3o do tabaco, n\u00e3o procure nada mais adequado do que\u00a0<b>Pod Juice Golden Custard E-juice<\/b>\u00a0para atender a todos os seus desejos em rela\u00e7\u00e3o ao e-juice. Que adiciona ousadamente sabores doces de baunilha e creme ao cl\u00e1ssico tabaco dourado. O sabor suave apresenta tr\u00eas n\u00edveis diferentes de nicotina, aumentando suas op\u00e7\u00f5es de vaporiza\u00e7\u00e3o personalizadas. Pod Juice Golden Custard traz para voc\u00ea um doce de tabaco como nenhum outro e com certeza ser\u00e1 seu suco eletr\u00f4nico com sabor de tabaco preferido.<\/p>\n<p class=\"second-title\">Recursos<\/p>\n<p>\u2022 Baunilha, creme e tabaco dourado<\/p>\n<p>\u2022 Garrafa Chubby Unic\u00f3rnio de 100 ml<\/p>\n<p>\u2022 Bon\u00e9 resistente a crian\u00e7as<\/p>\n<p>\u2022 70%VG<\/p>\n<p>\u2022 30%PG<\/p>\n<p>\u2022 Fabricado nos EUA<\/p>\n<p>\u2022 Dispon\u00edvel em 0 mg, 3 mg, 6 mg<\/p>\n<div class=\"title\">Pod Juice Golden Custard E-juice 100ml ESPECIFICA\u00c7\u00d5ES<\/div>\n<div class=\"especifica\u00e7\u00e3o\">\n<div class=\"splist\"><em>Tamanho da garrafa:<\/em>100ml<\/div>\n<div class=\"splist\"><em>Combina\u00e7\u00e3o de propor\u00e7\u00e3o:<\/em>70VG\/30PG<\/div>\n<div class=\"splist\"><em>N\u00edvel de nicotina:<\/em>0mg, 3mg, 6mg<\/div>\n<div class=\"splist\"><em>Perfil de sabor:<\/em>baunilha, creme, tabaco dourado<\/div>\n<\/div>\n<div class=\"title\">Pod Juice Golden Custard E-juice 100ml LISTA DE PACOTES<\/div>\n<p>1 Garrafa X Suco de Vagem E-suco de Creme Dourado<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pod Juice Golden Custard E-suco 100ml Marca:\u00a0Suco de vagem Unidade: conjunto Tipo: Suco Vape Peso l\u00edquido: 104(g) O custo combinado do frete ser\u00e1 calculado automaticamente pelo sistema ap\u00f3s voc\u00ea escolher o destino do frete na etapa de finaliza\u00e7\u00e3o da compra. Pod Juice Golden Custard E-juice 100ml INTRODU\u00c7\u00c3O Se voc\u00ea adora a experi\u00eancia de vaporiza\u00e7\u00e3o do [&#8230;]\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2992],"product_tag":[],"class_list":["post-274852","product","type-product","status-publish","product_cat-liquidos-para-cigarros-eletronicos","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product\/274852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/comments?post=274852"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/media?parent=274852"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_brand?post=274852"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_cat?post=274852"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_tag?post=274852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}