{"id":275044,"date":"2024-05-07T11:37:34","date_gmt":"2024-05-07T03:37:34","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/tropical-passion-orange-guava-vape-juice-naked-100-hawaiian-pog-e-juice-60ml-2\/"},"modified":"2026-06-23T18:33:10","modified_gmt":"2026-06-23T10:33:10","slug":"tropical-passion-orange-guava-vape-juice-naked-100-hawaiian-pog-e-juice-60ml","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/pt\/produto\/tropical-passion-orange-guava-vape-juice-naked-100-hawaiian-pog-e-juice-60ml\/","title":{"rendered":"Tropical Passion Orange Guava Vape Juice &#8211; Naked 100 Hawaiian POG E-juice 60ml"},"content":{"rendered":"<h2>Naked 100 Hawaiian POG E-juice 60ml<\/h2>\n<ul class=\"top\">\n<li style=\"list-style-type: nenhum\">\n<ul class=\"top\">\n<li>Marca:\u00a0Naked 100<\/li>\n<li>Unidade: conjunto<\/li>\n<li>Tipo: Suco Vape<\/li>\n<li>Peso l\u00edquido: 75(g)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>O custo combinado do frete ser\u00e1 calculado automaticamente pelo sistema ap\u00f3s voc\u00ea escolher o destino do frete na etapa de finaliza\u00e7\u00e3o da compra.<\/p>\n<div class=\"title\">Naked 100 Hawaiian POG E-juice INTRODU\u00c7\u00c3O<\/div>\n<p>Naked 100 Hawaiian POG\u00a0\u00e9 um produto e-l\u00edquido premium que oferece uma deliciosa mistura de sabores tropicais. Com uma propor\u00e7\u00e3o 70\/30 VG\/PG, este e-juice \u00e9 perfeito para produzir grandes nuvens de vapor, ao mesmo tempo que proporciona um golpe suave na garganta. O tamanho do frasco de 60ml \u00e9 pr\u00e1tico e duradouro. O perfil de sabor do POG havaiano apresenta uma combina\u00e7\u00e3o \u00fanica de maracuj\u00e1, laranja e goiaba perfeitamente equilibrada para criar uma experi\u00eancia de vaporiza\u00e7\u00e3o de dar \u00e1gua na boca. Este suco eletr\u00f4nico est\u00e1 dispon\u00edvel em dosagens de nicotina de 0 mg, 3 mg e 6 mg, tornando-o adequado para vapers novatos e experientes. Naked 100 Hawaiian POG E-juice 60ml \u00e9 uma experi\u00eancia obrigat\u00f3ria para quem gosta de sabores frutados e ex\u00f3ticos de suco eletr\u00f4nico.<\/p>\n<p>\u00a0<\/p>\n<p class=\"second-title\">Recursos<\/p>\n<p>\u2022 Garrafa Chubby Unic\u00f3rnio 60mL<\/p>\n<p>\u2022 65%VG<\/p>\n<p>\u2022 35%PG<\/p>\n<p>\u2022 Bon\u00e9 resistente a crian\u00e7as<\/p>\n<p>\u2022 Fabricado nos EUA<\/p>\n<p>\u2022 Nicotina dispon\u00edvel: 0 mg, 3 mg, 6 mg, 12 mg<\/p>\n<div class=\"title\">ESPECIFICA\u00c7\u00c3O DO suco eletr\u00f4nico POG havaiano Naked 100<\/div>\n<p>Tamanho da garrafa: 60ml<\/p>\n<p>VG\/PG: 35\/65<\/p>\n<p>Tipo de garrafa: Unic\u00f3rnio<\/p>\n<p>N\u00edvel de nicotina: 0mg, 3mg, 6mg, 12mg<\/p>\n<p>Perfil de Sabor: Maracuj\u00e1, Laranja, Goiaba<\/p>\n<div class=\"title\">LISTA DE PACOTES de suco eletr\u00f4nico POG havaiano Naked 100<\/div>\n<p>1 x suco eletr\u00f4nico POG havaiano Naked 100<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Naked 100 Hawaiian POG E-juice 60ml Marca:\u00a0Naked 100 Unidade: conjunto Tipo: Suco Vape Peso l\u00edquido: 75(g) O custo combinado do frete ser\u00e1 calculado automaticamente pelo sistema ap\u00f3s voc\u00ea escolher o destino do frete na etapa de finaliza\u00e7\u00e3o da compra. Naked 100 Hawaiian POG E-juice INTRODU\u00c7\u00c3O Naked 100 Hawaiian POG\u00a0\u00e9 um produto e-l\u00edquido premium que oferece [&#8230;]\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2992],"product_tag":[],"class_list":["post-275044","product","type-product","status-publish","product_cat-liquidos-para-cigarros-eletronicos","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product\/275044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/comments?post=275044"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/media?parent=275044"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_brand?post=275044"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_cat?post=275044"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_tag?post=275044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}