{"id":275050,"date":"2024-05-07T11:36:51","date_gmt":"2024-05-07T03:36:51","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/smooth-american-tobacco-vape-juice-2\/"},"modified":"2026-06-23T18:33:33","modified_gmt":"2026-06-23T10:33:33","slug":"smooth-american-tobacco-vape-juice","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/pt\/produto\/smooth-american-tobacco-vape-juice\/","title":{"rendered":"Smooth American Tobacco Vape Juice &#8211; Naked 100 Tobacco Euro Gold E-juice 60ml"},"content":{"rendered":"<h2>Naked 100 Tobacco Euro Gold E-juice 60ml<\/h2>\n<ul class=\"top\">\n<li style=\"list-style-type: nenhum\">\n<ul class=\"top\">\n<li>Marca:\u00a0Naked 100<\/li>\n<li>Unidade: conjunto<\/li>\n<li>Tipo: Suco Vape<\/li>\n<li>Peso l\u00edquido: 75(g)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>O custo combinado do frete ser\u00e1 calculado automaticamente pelo sistema ap\u00f3s voc\u00ea escolher o destino do frete na etapa de finaliza\u00e7\u00e3o da compra.<\/p>\n<div class=\"title\">Naked 100 Tobacco Euro Gold E-juice INTRODU\u00c7\u00c3O<\/div>\n<p>Este sabor\u00a0Naked 100 Tobacco\u00a0Euro Gold tem como objetivo trazer apenas o melhor sabor de tabaco do solo americano. Este suco vape com sabor de tabaco \u00e9 simplesmente aquele com o qual voc\u00ea n\u00e3o pode errar por causa de sua simplicidade e ra\u00edzes americanas. Este sabor vem em uma variedade de sabores de nicotina. Deixaremos voc\u00ea decidir quanta liberdade deseja com este sabor.<\/p>\n<p class=\"second-title\">Recursos<\/p>\n<p>\u2022 Garrafa Chubby Unic\u00f3rnio 60mL<\/p>\n<p>\u2022 Bon\u00e9 resistente a crian\u00e7as<\/p>\n<p>\u2022 65%VG<\/p>\n<p>\u2022 35%PG<\/p>\n<p>\u2022 Fabricado nos EUA<\/p>\n<p>\u2022 Dispon\u00edvel em 0 mg, 3 mg, 6 mg<\/p>\n<div class=\"title\">Naked 100 Tobacco Euro Gold E-juice ESPECIFICA\u00c7\u00c3O<\/div>\n<p>Tamanho da garrafa: 60ml<\/p>\n<p>VG\/PG: 65\/35<\/p>\n<p>Tipo de garrafa: Unic\u00f3rnio<\/p>\n<p>N\u00edvel de nicotina: 0mg, 3mg, 6mg<\/p>\n<p>Perfil de sabor: Rich American Tobacco<\/p>\n<div class=\"title\">Naked 100 Tobacco Euro Gold E-juice LISTA DE PACOTES<\/div>\n<p>1 x suco eletr\u00f4nico Naked 100 Tobacco Euro Gold<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Naked 100 Tobacco Euro Gold E-juice 60ml Marca:\u00a0Naked 100 Unidade: conjunto Tipo: Suco Vape Peso l\u00edquido: 75(g) O custo combinado do frete ser\u00e1 calculado automaticamente pelo sistema ap\u00f3s voc\u00ea escolher o destino do frete na etapa de finaliza\u00e7\u00e3o da compra. Naked 100 Tobacco Euro Gold E-juice INTRODU\u00c7\u00c3O Este sabor\u00a0Naked 100 Tobacco\u00a0Euro Gold tem como objetivo [&#8230;]\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2992],"product_tag":[],"class_list":["post-275050","product","type-product","status-publish","product_cat-liquidos-para-cigarros-eletronicos","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product\/275050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/comments?post=275050"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/media?parent=275050"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_brand?post=275050"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_cat?post=275050"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_tag?post=275050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}