{"id":275074,"date":"2024-05-07T11:30:07","date_gmt":"2024-05-07T03:30:07","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/cool-mint-blast-vape-juice-2\/"},"modified":"2026-06-23T18:35:49","modified_gmt":"2026-06-23T10:35:49","slug":"cool-mint-blast-vape-juice","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/pt\/produto\/cool-mint-blast-vape-juice\/","title":{"rendered":"Cool Mint Blast Vape Juice &#8211; Twist Mint No.1 E-juice 60ml"},"content":{"rendered":"<h2>Suco eletr\u00f4nico Twist Mint No.1<\/h2>\n<ul class=\"top\">\n<li style=\"list-style-type: nenhum\">\n<ul class=\"top\">\n<li>Marca:\u00a0<b>Twist<\/b><\/li>\n<li>Unidade: conjunto<\/li>\n<li>Tipo:\u00a0<b>Suco Vape<\/b><\/li>\n<li>Peso l\u00edquido: 105(g)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>O custo combinado do frete ser\u00e1 calculado automaticamente pelo sistema ap\u00f3s voc\u00ea escolher o destino do frete na etapa de finaliza\u00e7\u00e3o da compra.<\/p>\n<div class=\"title\">Twist Mint No.1 E-juice INTRODU\u00c7\u00c3O<\/div>\n<p><b>O suco eletr\u00f4nico Twist Mint No.1<\/b>\u00a0permite que voc\u00ea mergulhe no abra\u00e7o tentador da menta gelada, onde cada inspira\u00e7\u00e3o o transporta para um o\u00e1sis beijado pelo gelo. Com uma mistura meticulosamente elaborada, este e-juice proporciona uma explos\u00e3o de pura alegria mentolada, que lembra uma brisa fresca da montanha. As notas revigorantes de hortel\u00e3 e hortel\u00e3-pimenta dan\u00e7am em seu paladar, criando uma fus\u00e3o harmoniosa que \u00e9 ao mesmo tempo refrescante e satisfat\u00f3ria. Quer voc\u00ea seja um vaper experiente ou um novato.<\/p>\n<p class=\"second-title\">Recursos<\/p>\n<p>\u2022 Garrafa Unic\u00f3rnio de 60 ml*2<\/p>\n<p>\u2022 Bon\u00e9 resistente a crian\u00e7as<\/p>\n<p>\u2022 70%VG<\/p>\n<p>\u2022 30%PG<\/p>\n<p>\u2022 Formula\u00e7\u00e3o sint\u00e9tica de nicotina<\/p>\n<p>\u2022 Fabricado nos EUA<\/p>\n<p>\u2022 Dispon\u00edvel em 3mg, 6mg<\/p>\n<div class=\"title\">Twist Mint No.1 E-juice LISTA DE PACOTES<\/div>\n<p>1 * suco eletr\u00f4nico Twist Mint No.1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Suco eletr\u00f4nico Twist Mint No.1 Marca:\u00a0Twist Unidade: conjunto Tipo:\u00a0Suco Vape Peso l\u00edquido: 105(g) O custo combinado do frete ser\u00e1 calculado automaticamente pelo sistema ap\u00f3s voc\u00ea escolher o destino do frete na etapa de finaliza\u00e7\u00e3o da compra. Twist Mint No.1 E-juice INTRODU\u00c7\u00c3O O suco eletr\u00f4nico Twist Mint No.1\u00a0permite que voc\u00ea mergulhe no abra\u00e7o tentador da menta [&#8230;]\n","protected":false},"featured_media":339769,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2992],"product_tag":[],"class_list":["post-275074","product","type-product","status-publish","has-post-thumbnail","product_cat-liquidos-para-cigarros-eletronicos","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product\/275074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/comments?post=275074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/media\/339769"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/media?parent=275074"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_brand?post=275074"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_cat?post=275074"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_tag?post=275074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}