{"id":275080,"date":"2024-05-07T11:16:02","date_gmt":"2024-05-07T03:16:02","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/sweet-caramel-cream-vape-juice-2\/"},"modified":"2026-06-23T18:36:08","modified_gmt":"2026-06-23T10:36:08","slug":"sweet-caramel-cream-vape-juice","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/pt\/produto\/sweet-caramel-cream-vape-juice\/","title":{"rendered":"Sweet Caramel Cream Vape Juice &#8211; Mad Hatter Caramel Creme E-juice 60ml"},"content":{"rendered":"<h2>Suco eletr\u00f4nico de creme de caramelo do Chapeleiro Maluco<\/h2>\n<ul class=\"top\">\n<li>Marca:\u00a0<b>Chapeleiro Maluco<\/b><\/li>\n<li>Unidade: conjunto<\/li>\n<li>Tipo:\u00a0<b>Suco Vape<\/b><\/li>\n<li>Peso l\u00edquido: 100(g)<\/li>\n<\/ul>\n<p>O custo combinado do frete ser\u00e1 calculado automaticamente pelo sistema ap\u00f3s voc\u00ea escolher o destino do frete na etapa de finaliza\u00e7\u00e3o da compra.<\/p>\n<div class=\"title\">Mad Hatter Caramel Creme E-juice INTRODU\u00c7\u00c3O<\/div>\n<p><b>O suco eletr\u00f4nico Mad Hatter Caramel Creme\u00a0<\/b>vem com capacidade l\u00edquida de 60ml e duas op\u00e7\u00f5es de n\u00edvel de nicotina, incluindo 3mg e 6mg. Como o pr\u00f3prio nome sugere, Caramel Creme \u00e9 t\u00e3o doce e saboroso quanto o creme de caramelo da vida real. Cada baforada \u00e9 rica em sabor e fornece doses adequadas de nicotina. Quer voc\u00ea seja um amante de sobremesas ou um entusiasta de vaporiza\u00e7\u00e3o, o Chapeleiro Maluco sempre pode satisfazer suas necessidades. Lembre-se de usar um kit vape adequado para real\u00e7ar todo o sabor do suco eletr\u00f4nico Mad Hatter Caramel Creme.<\/p>\n<p class=\"second-title\">Recursos<\/p>\n<p>\u2022 Garrafa Chubby Gorilla de 60 ml<\/p>\n<p>\u2022 70%VG<\/p>\n<p>\u2022 30%PG<\/p>\n<p>\u2022 Formula\u00e7\u00e3o sint\u00e9tica de nicotina<\/p>\n<p>\u2022 Fabricado nos EUA<\/p>\n<p>\u2022 Nicotina dispon\u00edvel: 3mg, 6mg<\/p>\n<div class=\"title\">Mad Hatter Caramel Creme E-juice LISTA DE PACOTES<\/div>\n<p>1 x suco eletr\u00f4nico de creme de caramelo Mad Hatter<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Suco eletr\u00f4nico de creme de caramelo do Chapeleiro Maluco Marca:\u00a0Chapeleiro Maluco Unidade: conjunto Tipo:\u00a0Suco Vape Peso l\u00edquido: 100(g) O custo combinado do frete ser\u00e1 calculado automaticamente pelo sistema ap\u00f3s voc\u00ea escolher o destino do frete na etapa de finaliza\u00e7\u00e3o da compra. Mad Hatter Caramel Creme E-juice INTRODU\u00c7\u00c3O O suco eletr\u00f4nico Mad Hatter Caramel Creme\u00a0vem com [&#8230;]\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2992],"product_tag":[],"class_list":["post-275080","product","type-product","status-publish","product_cat-liquidos-para-cigarros-eletronicos","first","instock","sale","shipping-taxable","product-type-external"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product\/275080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/comments?post=275080"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/media?parent=275080"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_brand?post=275080"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_cat?post=275080"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_tag?post=275080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}