{"id":330204,"date":"2020-11-11T12:23:47","date_gmt":"2020-11-11T04:23:47","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/relx-infinity-kit-1-pod-system-2-pods-2\/"},"modified":"2026-06-24T08:41:44","modified_gmt":"2026-06-24T00:41:44","slug":"relx-infinity-kit-1-pod-system-2-pods","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/pt\/produto\/relx-infinity-kit-1-pod-system-2-pods\/","title":{"rendered":"Kit Relx Infinity (1 sistema de pod + 2 pods)"},"content":{"rendered":"<h1>Relax infinito a qualquer hora, em qualquer lugar<\/h1>\n<p>Carregamento sem fio de longa dura\u00e7\u00e3o da bateria com interface de carregamento magn\u00e9tico integrada: n\u00e3o h\u00e1 necessidade de alinhar a linha do plugue, pousar e carregar e, em seguida, v\u00e1rios acess\u00f3rios para desbloquear mais cenas. Controle de temperatura est\u00e1vel: A temperatura m\u00e1xima do n\u00facleo de atomiza\u00e7\u00e3o \u00e9 controlada em cerca de 230 \u00b0 C para melhorar a estabilidade do aquecimento, de modo que o g\u00e1s de combust\u00e3o se torne delicado e texturizado, e a boca fique muito suave.<\/p>\n<p>Rela\u00e7\u00e3o ergon\u00f4mica: ap\u00f3s ajustes precisos de estilo do 26, a curva c\u00f4ncava arredondada envolve confortavelmente as contas e os picos dos l\u00e1bios, com uma forte sensa\u00e7\u00e3o de ajuste, n\u00e3o importa o que a boca n\u00e3o vaze.<\/p>\n<p>F\u00f3rmula especial de pesquisa: Relx \u00e9 uma f\u00f3rmula especial de \u00f3leo de fuma\u00e7a da &#8220;S\u00e9rie Infinita&#8221;. Al\u00e9m do paladar mais evidente, a fuma\u00e7a fica mais condensada e grudenta, e haver\u00e1 uma sensa\u00e7\u00e3o de plenitude na boca.<\/p>\n<p>Silicone \u00e0 prova de vazamentos: \u00c9 mais adequado para envolver o n\u00facleo de atomiza\u00e7\u00e3o para evitar que o \u00f3leo de fuma\u00e7a vaze da caixa de armazenamento de \u00f3leo * Estrutura de labirinto 11-layer: estrutura de labirinto extra-longa, que bloqueia o condensado e a fuma\u00e7a na c\u00e2mara de atomiza\u00e7\u00e3o. Rede \u00e0 prova de \u00f3leo de 0,35 mm: A tens\u00e3o superficial do l\u00edquido formado pelo \u00f3leo de fuma\u00e7a no tamanho do orif\u00edcio de 0,35 mm apenas neutraliza a gravidade e coopera com as almofadas de algod\u00e3o ao redor para formar a parti\u00e7\u00e3o final.<\/p>\n<p>Relx Infinity Conjunto de fuma\u00e7a de atomiza\u00e7\u00e3o com recarga infinita, vendido em lojas de Hong Kong, todos originais licenciados, garantia local de um ano. Entre eles est\u00e3o o preto fosco, o prata gelado e o vermelho areia. O pedido no mesmo dia \u00e9 entregue no dia seguinte, frete gr\u00e1tis, consulta pelo WhatsApp (+852) 70747874<\/p>\n<h2>Conte\u00fado da embalagem:<\/h2>\n<p>Cigarro Bateria X 1<br \/>\nCapacidade da bateria: 380mAh<br \/>\nCorrente m\u00e1xima de carregamento da bateria: 700mA<br \/>\nVagens X 2<br \/>\nConte\u00fado l\u00edquido da c\u00e1psula: 2ml X 2<br \/>\nConte\u00fado de nicotina: 3% \/ 5%<br \/>\nCabo de carregamento USB tipo C X 1<br \/>\nSabor interno das vagens:\u00a0 menta 5%, feij\u00e3o mungo gelado 3%<br \/>\nPrincipais componentes das bombas de cigarro: glicerina, propilenoglicol, especiarias, sal de nicotina<\/p>\n<p>Compat\u00edvel com pods: Relx Infinity Pods Oversea Edition, pods Relx Infinity e Veex Pods<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Relax infinito a qualquer hora, em qualquer lugar Carregamento sem fio de longa dura\u00e7\u00e3o da bateria com interface de carregamento magn\u00e9tico integrada: n\u00e3o h\u00e1 necessidade de alinhar a linha do plugue, pousar e carregar e, em seguida, v\u00e1rios acess\u00f3rios para desbloquear mais cenas. Controle de temperatura est\u00e1vel: A temperatura m\u00e1xima do n\u00facleo de atomiza\u00e7\u00e3o \u00e9 [&#8230;]\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2998],"product_tag":[],"class_list":["post-330204","product","type-product","status-publish","product_cat-starter-kits-2","first","instock","sale","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product\/330204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/comments?post=330204"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/media?parent=330204"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_brand?post=330204"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_cat?post=330204"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_tag?post=330204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}