{"id":330216,"date":"2020-11-11T12:23:46","date_gmt":"2020-11-11T04:23:46","guid":{"rendered":"https:\/\/shop.vape.hk\/product\/gippro-gp6-japan-food-standard-vape-starter-kit-1device-and-2-pods-2\/"},"modified":"2026-06-24T08:43:24","modified_gmt":"2026-06-24T00:43:24","slug":"gippro-gp6-japan-food-standard-vape-starter-kit-1device-and-2-pods","status":"publish","type":"product","link":"https:\/\/shop.vape.hk\/pt\/produto\/gippro-gp6-japan-food-standard-vape-starter-kit-1device-and-2-pods\/","title":{"rendered":"Kit Gippro GP6 Japan Starter (1 dispositivo e 2 pods)"},"content":{"rendered":"<h1>Gipro GP6 Engenhosidade japonesa<\/h1>\n<div>O produto mais recente da Gippro GP6 \u00e9 mais popular no Jap\u00e3o. A apar\u00eancia moderna faz com que se torne uma nova tend\u00eancia para fumar com a m\u00e3o esquerda, e existe uma vers\u00e3o sem nicotina. Ele foi pensado para voc\u00ea que quer parar de fumar mas quer se manter na moda!<br \/>\nEste conjunto cont\u00e9m o sistema de pod e 2 pods<\/div>\n<p>\u00a0<\/p>\n<div><\/div>\n<div>Gippro GP6 personaliza\u00e7\u00e3o dividida Design ergon\u00f4mico de cigarro eletr\u00f4nico, sem arestas e cantos afiados, ader\u00eancia suave usando revestimento da marca de carro esportivo Ferrari, prote\u00e7\u00e3o ambiental e valor nominal. Processo de tratamento da superf\u00edcie da pele do beb\u00ea, proporcionando uma sensa\u00e7\u00e3o de pele de beb\u00ea. Japan Smart Air O n\u00facleo de personaliza\u00e7\u00e3o din\u00e2mica melhora a suavidade em 3 vezes e reduz os problemas de vazamento de \u00f3leo e \u00f3leo gorduroso. O bico se adapta perfeitamente ao formato dos l\u00e1bios e o processo de n\u00edvel nano \u00e9 seco e antibacteriano.<\/div>\n<div><\/div>\n<div><\/div>\n<div>\n<p>\ud83c\uddef\ud83c\uddf5 O \u00fanico no mercado a obter quarentena inofensiva de qualidade alimentar japonesa<br \/>\n\ud83c\uddef\ud83c\uddf5A \u00fanica glicerina natural do mercado<br \/>\n\ud83c\uddef\ud83c\uddf5 O \u00fanico propilenoglicol de qualidade alimentar do mercado<br \/>\n\ud83c\uddef\ud83c\uddf5 O \u00fanico sal de nicotina org\u00e2nico do mercado<br \/>\n\ud83c\uddef\ud83c\uddf5 \u00danico fornecedor japon\u00eas Hasegawa Spice do mercado<br \/>\n\ud83c\uddef\ud83c\uddf5 \u00danico mercado aprovado pelo Minist\u00e9rio da Sa\u00fade, Trabalho e Previd\u00eancia<\/p>\n<h2>Especifica\u00e7\u00e3o:<\/h2>\n<ul>\n<li>Tamanho do corpo: 100.2mm * 25.5mm * 12mm<br \/>\nPeso corporal: 0,19kg<br \/>\nCapacidade da bateria: 400mAh<br \/>\nTempo de carregamento: 70 minutos<br \/>\nTens\u00e3o da bateria: 3,7V<br \/>\nCapacidade do nebulizador: 2,0 ml<br \/>\nConte\u00fado: 1 m\u00e1quina + 2 cartuchos<br \/>\nCont\u00e9m sabor de bomba de fuma\u00e7a: menta fresca 0mg, toranja manga 0mg<\/li>\n<\/ul>\n<p>lista de embalagem:<\/p>\n<ul>\n<li>Caixa de embalagem<br \/>\nCaixa envelope<br \/>\nguia do usu\u00e1rio<br \/>\nP\u00f3lo da bateria<br \/>\nNebulizador * 2<br \/>\nCabo de dados USB<br \/>\ncertificado<\/li>\n<\/ul>\n<p><strong>Pod compat\u00edvel: pod Gipro GP6<\/strong><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gipro GP6 Engenhosidade japonesa O produto mais recente da Gippro GP6 \u00e9 mais popular no Jap\u00e3o. A apar\u00eancia moderna faz com que se torne uma nova tend\u00eancia para fumar com a m\u00e3o esquerda, e existe uma vers\u00e3o sem nicotina. Ele foi pensado para voc\u00ea que quer parar de fumar mas quer se manter na moda! [&#8230;]\n","protected":false},"featured_media":337058,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2994],"product_tag":[],"class_list":["post-330216","product","type-product","status-publish","has-post-thumbnail","product_cat-hnb-2","first","instock","sale","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"jetpack_sharing_enabled":true,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product\/330216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/comments?post=330216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/media\/337058"}],"wp:attachment":[{"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/media?parent=330216"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_brand?post=330216"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_cat?post=330216"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.vape.hk\/pt\/wp-json\/wp\/v2\/product_tag?post=330216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}